{"id":795,"date":"2017-02-03T23:24:30","date_gmt":"2017-02-04T01:24:30","guid":{"rendered":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/?p=795"},"modified":"2017-02-04T13:48:05","modified_gmt":"2017-02-04T15:48:05","slug":"joia-rara-quem-e-quem","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/","title":{"rendered":"Joia Rara: Quem \u00e9 quem"},"content":{"rendered":"<p><strong>Principais personagens<\/strong><\/p>\n<p><b>Franz (Bruno Gagliasso)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq01.jpg\" \/><br \/>\nFilho primog\u00eanito do poderoso empres\u00e1rio Ernest Hauser. Franz foi preparado a vida toda para substituir o pai na dire\u00e7\u00e3o da joalheria e da fundi\u00e7\u00e3o que levam o nome da fam\u00edlia. N\u00e3o acredita em for\u00e7as sobrenaturais e acha que cada pessoa constr\u00f3i seu pr\u00f3prio destino. Foi casado com Am\u00e9lia, com quem teve uma filha, P\u00e9rola.<\/p>\n<p><b>Am\u00e9lia (Bianca Bin)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq02.jpg\" \/><br \/>\nmigrante nordestina, \u00e9 uma mulher batalhadora. Veio para o Rio ao lado do irm\u00e3o, Mundo, em busca de melhores condi\u00e7\u00f5es de vida. Depois da morte do pai, foi criada pelo padrinho, Apol\u00f4nio. Ao conhecer Franz, os dois se apaixonaram e tiveram uma filha, P\u00e9rola.<\/p>\n<p><b>Manfred (Carmo Dalla Vecchia)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq03.jpg\" \/><br \/>\nFilho bastardo de Ernest com Gertrude, a governanta da casa, guarda um grande rancor por nunca ter sido reconhecido pelo pai. Tem uma profunda inveja de Franz, seu meio-irm\u00e3o e eterno rival, mas nunca deixa isso transparecer para os outros. Seu grande objetivo \u00e9 arruinar a fam\u00edlia Hauser e tirar de Franz tudo que ele tem de mais precioso.<\/p>\n<p><b>Iolanda (Carolina Dieckmann)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq04.jpg\" \/><br \/>\nNamorou por muitos anos com Mundo, com quem sonhava em casar. Para salvar o pai, Vanceslau, acabou tendo que aceitar se casar com Ernest. Depois de muito sofrimento, conseguiu se separar do empres\u00e1rio e voltou a ficar com Mundo.<\/p>\n<p><b>Mundo (Domingos Montagner<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq05.jpg\" \/><br \/>\nIrm\u00e3o de Am\u00e9lia. L\u00edder nato, trabalhou na fundi\u00e7\u00e3o Hauser e sempre foi uma refer\u00eancia para os oper\u00e1rios. Tornou-se deputado para lutar pelos direitos dos trabalhadores. Seu grande amor \u00e9 Iolanda.<\/p>\n<p><b>S\u00edlvia (Nathalia Dill)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq06.jpg\" \/><br \/>\nS\u00edlvia culpa Ernest pela ru\u00edna de seu pai e jurou se vingar a qualquer custo. Lind\u00edssima, esperta e sedutora, n\u00e3o poupa esfor\u00e7os para ver a fam\u00edlia Hauser destru\u00edda. Casou-se com Franz para poder executar seu plano de vingan\u00e7a, mas acabou se apaixonando por Viktor, com quem teve um filho.<\/p>\n<p><b>P\u00e9rola (Mel Maia)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq07.jpg\" \/><br \/>\nReencarna\u00e7\u00e3o de Ananda. \u00c9 filha de Franz e Am\u00e9lia. Amada por todos, \u00e9 carinhosa e muito esperta para sua idade. \u00c9 a \u00fanica pessoa capaz de apaziguar as brigas entre as fam\u00edlias dos pais.<\/p>\n<p><b>Ananda (Nelson Xavier)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq08.jpg\" \/><br \/>\nL\u00edder espiritual do templo Padma Ling. S\u00e1bio e carism\u00e1tico, tem sempre um conselho para aqueles que precisam de orienta\u00e7\u00e3o. Fez sua passagem e reencarnou no Brasil como a menina P\u00e9rola, filha de Franz e Am\u00e9lia.<\/p>\n<p><b>Apol\u00f4nio (Luis Gustavo)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq09.jpg\" \/><br \/>\nPadrinho de Am\u00e9lia e Mundo, criou os dois como se fossem seus pr\u00f3prios filhos. \u00c9 um bom homem e muito carinhoso com os afilhados.<\/p>\n<p><b>Toni (Thiago Lacerda)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq10.jpg\" \/><br \/>\nImigrante italiano. Por muito tempo foi membro do partido comunista e lutou pelos direitos trabalhistas dos oper\u00e1rios ao lado de sua primeira mulher, Gaia. Com a pris\u00e3o dos comunistas, foi separado dela e do filho rec\u00e9m-nascido, que foram deportados do Brasil. Casou-se com Hilda, com quem trabalha em um armaz\u00e9m.<\/p>\n<p><b>Aurora (Mariana Ximenes)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq11.jpg\" \/><br \/>\nVedete brasileira que fez muito sucesso na Fran\u00e7a e voltou ao Brasil para reaver o dinheiro que D\u00e9cio deve a ela. Tornou-se a grande estrela do Cabar\u00e9 Pacheco Le\u00e3o. \u00c9 uma artista ousada e de esp\u00edrito livre.<\/p>\n<p><b>Lola (Leticia Spiller)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq12.jpg\" \/><br \/>\nPor muito tempo, foi a principal vedete do Cabar\u00e9 Pacheco Le\u00e3o. \u00c9 muito vaidosa e acha que tem sempre que ser o centro das aten\u00e7\u00f5es. Tem uma grande rivalidade com Aurora, que roubou seu posto de estrela do cabar\u00e9.<\/p>\n<p><b>Ernest (Jos\u00e9 de Abreu)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq13.jpg\" \/><br \/>\nDe origem su\u00ed\u00e7a, \u00e9 o poderoso dono da joalheria e da fundi\u00e7\u00e3o Hauser. Inescrupuloso e conservador, \u00e9 conhecido por explorar os trabalhadores da empresa. Vi\u00favo, criou os filhos de acordo com seus valores e tra\u00e7ou planos bem definidos para todos eles. Quando deseja alguma coisa, n\u00e3o deixa nada impedi-lo de conquistar seus objetivos.<\/p>\n<p><b>Arlindo (Marcos Caruso)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq14.jpg\" \/><br \/>\nDono e diretor do Cabar\u00e9 Pacheco Le\u00e3o, \u00e9 um grande entusiasta das artes e apaixonado pelo que faz. Vive levando pux\u00f5es de orelha da esposa, Miquelina, pois ela acha que ele est\u00e1 sempre se engra\u00e7ando para as coristas e vedetes da companhia.<\/p>\n<p><b>Tenpa (\u00c2ngelo Ant\u00f4nio)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq15.jpg\" \/><br \/>\nMonge do templo Padma Ling. Depois de Ananda, \u00e9 o mais velho do grupo de monges. S\u00e1bio, paciente, engra\u00e7ado e exc\u00eantrico.<\/p>\n<p><b>Sonan (Caio Blat)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq16.jpg\" \/><br \/>\nJovem monge do templo Padma Ling, \u00e9 filho de m\u00e3e brasileira. Disc\u00edpulo de Ananda, foi criado por seu mestre depois da morte da m\u00e3e. \u00c9 muito s\u00e9rio, exigente e disciplinado. Sua miss\u00e3o \u00e9 encontrar a reencarna\u00e7\u00e3o de Ananda. Ao conhecer Matilde, se apaixonou por ela, mas n\u00e3o consegue lidar com esse sentimento.<\/p>\n<p><b>Santinha (Nicette Bruno)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq17.jpg\" \/><br \/>\nM\u00e3e de Miquelina, de santa s\u00f3 tem o nome. N\u00e3o perde uma oportunidade de infernizar a vida dos familiares e, especialmente, do genro, Arlindo.<\/p>\n<p><b>Venceslau (Reginaldo Faria)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq18.jpg\" \/><br \/>\nPai de Iolanda, trabalhou por anos como contador na empresa de Ernest. Filho de um rico comerciante espanhol, perdeu quase todo o dinheiro da fam\u00edlia no jogo e hoje vive no corti\u00e7o.<\/p>\n<p><b>Gertrude (Ana Lucia Torre)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq19.jpg\" \/><br \/>\nGovernanta da mans\u00e3o Hauser. Tem uma verdadeira adora\u00e7\u00e3o por Ernest, com quem teve um filho bastardo, Manfred. Ela sonha com o dia em que o patr\u00e3o reconhecer\u00e1 que ela \u00e9 a esposa perfeita para ele.<\/p>\n<p><b>Gaia (Ana Cec\u00edlia Costa)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq20.jpg\" \/><br \/>\nImigrante lituana, trabalhava na fundi\u00e7\u00e3o Hauser. Como integrante do partido comunista, participava intensamente da luta oper\u00e1rio por direitos trabalhistas ao lado do marido, Toni. Com a persegui\u00e7\u00e3o aos comunistas, foi deportada do Brasil junto com o filho. Voltou ao Brasil em busca de seu filho desaparecido.<\/p>\n<p><b>Matilde (Fabiula Nascimento)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq21.jpg\" \/><br \/>\nVedete no Cabar\u00e9 Pacheco Le\u00e3o. De origem humilde, veio tentar a carreira de artista no Rio de Janeiro. \u00c9 muito bondosa e gosta de ajudar os outros. Apaixonou-se por Sonan e tem que lidar com a impossibilidade de concretizar seu amor.<\/p>\n<p><b>D\u00e1lia (Tania Khalill)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq22.jpg\" \/><br \/>\nCorista no Cabar\u00e9 Pacheco Le\u00e3o. \u00c9 irm\u00e3 de Davi.<\/p>\n<p><b>Miquelina (Rosi Campos)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq23.jpg\" \/><br \/>\nDona do Cabar\u00e9 Pacheco Le\u00e3o, faz de tudo na companhia. Mulher de g\u00eanio forte e explosivo, vive brigando com o marido, Arlindo. Mesmo vivendo entre tapas e beijos, os dois se amam.<\/p>\n<p><b>Laura (Claudia Ohana)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq24.jpg\" \/><br \/>\nEsposa de Valter, m\u00e3e de Eurico e D\u00e9cio. Depois da morte de Eurico, convencer o marido a adotar mais um filho, Tavinho.<\/p>\n<p><b>Joel (Marcelo M\u00e9dici)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq25.jpg\" \/><br \/>\nSecret\u00e1rio e companheiro insepar\u00e1vel de Aurora, est\u00e1 sempre bajulando sua grande musa. Gosta de uma intriga e de ver o circo pegar fogo.<\/p>\n<p><b>Volpina (Paula Burlamaqui)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq26.jpg\" \/><br \/>\nLavadeira, vive no corti\u00e7o e est\u00e1 sempre fofocando sobre o que acontece com os vizinhos. Tem um caso com Valter e vive esnobando Venceslau.<\/p>\n<p><b>Fabr\u00edcio (Ricardo Pereira)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq27.jpg\" \/><br \/>\nImigrante portugu\u00eas, \u00e9 militante do partido comunista. \u00c9 amigo de Mundo e Toni.<\/p>\n<p><b>Hilda (Luiza Valdetaro)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq28.jpg\" \/><br \/>\nFilha mais nova de Ernest, teve uma educa\u00e7\u00e3o muito r\u00edgida. Seu pai sempre esperou que ela se casasse com um homem de bem, mas ela se apaixonou por Toni e os dois se casaram. Sonha em ser cantora.<\/p>\n<p><b>Odilon (Tiago Abravanel)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq29.jpg\" \/><br \/>\nVivia como um malandro t\u00edpico da \u00e9poca, mas conseguiu realizar seu grande sonho, tornando-se cantor no Cabar\u00e9 Pacheco Le\u00e3o.<\/p>\n<p><b>D\u00e9cio (Miguel R\u00f4mulo)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq30.jpg\" \/><br \/>\nFilho de Valter e Laura, voltou ao Brasil depois de terminar os estudos na Europa. Mimado e desagrad\u00e1vel, s\u00f3 pensa em si mesmo. Despreza Tavinho, seu irm\u00e3o adotivo, e n\u00e3o perde uma chance de humilh\u00e1-lo.<\/p>\n<p><b>Viktor (Rafael Cardoso)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq31.jpg\" \/><br \/>\nFilho do meio de Ernest, teve a mesma educa\u00e7\u00e3o r\u00edgida de seus irm\u00e3os. Sens\u00edvel e apaixonado pelas artes, seu grande sonho \u00e9 se tornar pintor, o que \u00e9 impens\u00e1vel para seu pai. Apaixonou-se por S\u00edlvia e os dois tiveram um filho.<\/p>\n<p><b>Valter (Leopoldo Pacheco)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq32.jpg\" \/><br \/>\nCasado com Laura, com quem teve dois filhos: Eurico e D\u00e9cio. \u00c9 diretor do clube dos 100. Homem conservador, \u00e9 grande amigo de Ernest. Depois da morte de Eurico, aceitou adotar mais um filho, Tavinho, para quem n\u00e3o d\u00e1 muita aten\u00e7\u00e3o.<\/p>\n<p><b>Creotina (Luana Martau)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq33.jpg\" \/><br \/>\nSobrinha de Concei\u00e7\u00e3o, com quem trabalha na pens\u00e3o. Odeia o pr\u00f3prio nome e exige que todos a chamem de Cl\u00e9o. Tem uma mania feia de pegar as coisas dos outros.<\/p>\n<p><b>Arlindinho (Pedro Neschling)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq34.jpg\" \/><br \/>\nFilho mais velho de Arlindo e Miquelina, trabalha no cabar\u00e9 com os pais. Apaixonado por Serena.<\/p>\n<p><b>Dona Concei\u00e7\u00e3o (Cl\u00e1udia Missura)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq35.jpg\" \/><br \/>\nDona da pens\u00e3o na Lapa. Est\u00e1 sempre preocupada em economizar e vive dando pux\u00f5es de orelha nos moradores quando eles esquecem a luz ligada, gastam muita \u00e1gua no banho, querem comer demais ou n\u00e3o pagam em dia.<\/p>\n<p><b>Lindinha (Cacau Prot\u00e1sio)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq36.jpg\" \/><br \/>\nFilha de C\u00edcero e irm\u00e3 de Isa\u00edas, Josu\u00e9 e Caetano. Mora no corti\u00e7o.<\/p>\n<p><b>Belmira (Juliana Lohmann)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq37.jpg\" \/><br \/>\nFilha mais nova de Arlindo e Miquelina. T\u00edmida e atrapalhada, \u00e9 o patinho feio da fam\u00edlia. \u00c9 apaixonada por Nuno.<\/p>\n<p><b>Davi (Leandro Lima)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq38.jpg\" \/><br \/>\nIrm\u00e3o de D\u00e1lia. Lutou na Segunda Guerra Mundial, onde foi ferido e acabou paral\u00edtico. Depois disso, tornou-se um homem amargurado e s\u00f3 conseguiu superar a depress\u00e3o ao conhecer Aurora.<\/p>\n<p><b>Etelvino (Glic\u00e9rio do Ros\u00e1rio)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq39.jpg\" \/><br \/>\nOper\u00e1rio da Fundi\u00e7\u00e3o Hauser.<\/p>\n<p><b>Isa\u00edas (Land Vieira)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq40.jpg\" \/><br \/>\nFilho de C\u00edcero e irm\u00e3o de Lindinha, Josu\u00e9 e Caetano. Trabalhou por um tempo como motorista de Ernest e Iolanda.<\/p>\n<p><b>Artur (\u00cdcaro Silva)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq41.jpg\" \/><br \/>\nArtista muito talentoso, \u00e9 amigo de Viktor. Trabalha na livraria. Apaixonado por Laura.<\/p>\n<p><b>Cristina (Giovanna Ewbank)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq42.jpg\" \/><br \/>\nCorista no Cabar\u00e9 Pacheco Le\u00e3o. \u00c9 bonita, talentosa e um pouco avoada.<\/p>\n<p><b>Zilda (Aninha Lima)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq43.jpg\" \/><br \/>\nCorista no Cabar\u00e9 Pacheco Le\u00e3o.<\/p>\n<p><b>Elisa (Guta Ruiz)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq44.jpg\" \/><br \/>\nCorista no Cabar\u00e9 Pacheco Le\u00e3o.<\/p>\n<p><b>Nuno (Renato Go\u00e9s)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq45.jpg\" \/><br \/>\nRapaz muito competente e dedicado, trabalhou como assistente de Venceslau na Fundi\u00e7\u00e3o Hauser. Foi for\u00e7ado e pedir demiss\u00e3o e conseguiu emprego como contador no cabar\u00e9.<\/p>\n<p><b>Serena Fox (Simone Gutierrez)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq46.jpg\" \/><br \/>\nVedete no Cabar\u00e9 Pacheco Le\u00e3o. \u00c9 gordinha e muito bem resolvida com seu corpo. \u00c9 adorada pelo p\u00fablico masculino do cabar\u00e9. Tem um caso com Arlindinho.<\/p>\n<p><b>Zefinha (Cristiane Amorim)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq47.jpg\" \/><br \/>\nPrima de Am\u00e9lia, veio do nordeste para o Rio de Janeiro com o sonho de subir na vida. Tenta de todo jeito esconder suas origens nordestinas.<\/p>\n<p><b>Jampa (Fabio Yoshihara)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq48.jpg\" \/><br \/>\nMonge do templo Padma Ling. Muito s\u00e1bio, tem um vasto conhecimento sobre astrologia.<\/p>\n<p><b>Josias (Adelio Lima)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq49.jpg\" \/><br \/>\nTrabalha na Fundi\u00e7\u00e3o Hauser como encarregado, coordenando os oper\u00e1rios. Segue \u00e0 risca as ordens dos patr\u00f5es.<\/p>\n<p><b>Curi\u00f3 (Michel Gomes)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq50.jpg\" \/><br \/>\nOper\u00e1rio da Fundi\u00e7\u00e3o Hauser.<\/p>\n<p><b>Rigpa (Adriano Bolshi)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq51.jpg\" \/><br \/>\nMonge do templo Padma Ling. Gordinho, engra\u00e7ado e afetuoso, \u00e9 o cozinheiro do templo.<\/p>\n<p><b>C\u00edcero (Jorge Maya)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq52.jpg\" \/><br \/>\nEx-motorista de Ernest, sempre foi muito fiel ao patr\u00e3o. Depois de se aposentar, comprou o bar frequentado pelos oper\u00e1rios da fundi\u00e7\u00e3o e trabalha l\u00e1. \u00c9 pai de Isa\u00edas, Lindinha, Jous\u00e9 e Caetano.<\/p>\n<p><b>Mama Francesca (Norma Blum)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq53.jpg\" \/><br \/>\nItaliana, \u00e9 a m\u00e3e de Toni. Vive com o filho no corti\u00e7o. \u00c9 grande amiga de Apol\u00f4nio.<\/p>\n<p><b>Pilar (Silvia Salgado)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq54.jpg\" \/><br \/>\n\u00c9 a elegante vendedora da joalheria Hauser. Mora na pens\u00e3o de Dona Concei\u00e7\u00e3o. Fingia ser amiga de S\u00edlvia a mando de Manfred.<\/p>\n<p><b>Benito (Anthero Montenegro)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq55.jpg\" \/><br \/>\nMembro do movimento integralista, obedece ordens de Manfred.<\/p>\n<p><b>Margarida (Maria Gal)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq56.jpg\" \/><br \/>\nLavadeira, vive no corti\u00e7o e est\u00e1 sempre fofocando sobre o que acontece com os vizinhos.<\/p>\n<p><b>Dr. Rubens (Marcos Damigo)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq57.jpg\" \/><br \/>\nM\u00e9dico que atende a popula\u00e7\u00e3o pobre que mora no corti\u00e7o. Faz o tratamento com Davi para que ele possa voltar a andar.<\/p>\n<p><b>Rosa (Karine Carvalho)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq58.jpg\" \/><br \/>\nLavadeira, vive no corti\u00e7o e est\u00e1 sempre fofocando sobre o que acontece com os vizinhos.<\/p>\n<p><b>Josu\u00e9 (Alexandre Rodrigues)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq59.jpg\" \/><br \/>\nMotorista na casa de Ernest. Filho de C\u00edcero e irm\u00e3o de Lindinha, Isa\u00edas e Caetano.<\/p>\n<p><b>Julieta (Bia Guedes)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq60.jpg\" \/><br \/>\nTrabalhou muitos anos como empregada na mans\u00e3o de Ernest. Vive no corti\u00e7o e \u00e9 amiga de inf\u00e2ncia de Iolanda.<\/p>\n<p><b>Dr. Moacir (M\u00e1rcio Ehrlich)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq61.jpg\" \/><br \/>\nAdvogado de confian\u00e7a de Ernest e Manfred.<\/p>\n<p><b>Dr. Silveira (Gustavo Trestini)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq62.jpg\" \/><br \/>\nAdvogado que defende as causas dos moradores do corti\u00e7o.<\/p>\n<p><b>Peteleco (Jo\u00e3o Fernandes)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq63.jpg\" \/><br \/>\nMenino \u00f3rf\u00e3o, era explorado em uma carvoaria controlada por integralistas. Conseguiu fugir e chegar \u00e0 cidade.<\/p>\n<p><b>Norbu (Adriano Alves)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq64.jpg\" \/><br \/>\nVive no mosteiro Padma Ling, onde estuda para ser monge budista. Ao conhecer P\u00e9rola, torna-se amigo e confidente da menina.<\/p>\n<p><b>Caetano (Max Lima)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq65.jpg\" \/><br \/>\nMelhor amigo de P\u00e9rola, jogam futebol sempre que podem. Filho de C\u00edcero, \u00e9 irm\u00e3o mais novo de Lindinha Josu\u00e9 e Isa\u00edas.<\/p>\n<p><b>Tavinho (Xande Valois)<\/b><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq66.jpg\" \/><br \/>\n\u00d3rf\u00e3o, foi adotado de maneira discreta e misteriosa por Laura e Valter para suprir a perda de Eurico. Tem que lidar com a rejei\u00e7\u00e3o do pai adotivo e o desprezo de D\u00e9cio, seu irm\u00e3o mais velho. \u00c9 o filho desaparecido de Toni e Gaia.<\/p>\n<p><b>Leia tamb\u00e9m:<\/b><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara\/\">Joia Rara: Uma hist\u00f3ria de uma paix\u00e3o proibida<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Principais personagens Franz (Bruno Gagliasso) Filho primog\u00eanito do poderoso empres\u00e1rio Ernest Hauser. Franz foi preparado a vida toda para substituir o pai na dire\u00e7\u00e3o da joalheria e da fundi\u00e7\u00e3o que levam o nome da fam\u00edlia. N\u00e3o acredita em for\u00e7as sobrenaturais e acha que cada pessoa constr\u00f3i seu pr\u00f3prio destino. Foi casado com Am\u00e9lia, com quem &#8230; <a title=\"Joia Rara: Quem \u00e9 quem\" class=\"read-more\" href=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/\" aria-label=\"More on Joia Rara: Quem \u00e9 quem\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[9],"class_list":["post-795","post","type-post","status-publish","format-standard","hentry","category-blog","tag-personagens"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Paulo Ant\u00f4nio\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Arquivo de Novelas | Tramas e personagens\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Joia Rara: Quem \u00e9 quem | Arquivo de Novelas\" \/>\n\t\t<meta property=\"og:description\" content=\"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-02-04T01:24:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-02-04T15:48:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tevenovelas\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@tvnovelas\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Joia Rara: Quem \u00e9 quem | Arquivo de Novelas\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@tvnovelas\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#article\",\"name\":\"Joia Rara: Quem \\u00e9 quem | Arquivo de Novelas\",\"headline\":\"Joia Rara: Quem \\u00e9 quem\",\"author\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/author\\\/pauloantoniocaetenews-com-br\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.caetenews.com.br\\\/page\\\/media\\\/62\\\/joiararaqq01.jpg\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#articleImage\"},\"datePublished\":\"2017-02-03T23:24:30-02:00\",\"dateModified\":\"2017-02-04T13:48:05-02:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#webpage\"},\"articleSection\":\"Blog, Personagens\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#listItem\",\"name\":\"Joia Rara: Quem \\u00e9 quem\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#listItem\",\"position\":3,\"name\":\"Joia Rara: Quem \\u00e9 quem\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/#organization\",\"name\":\"TV Novelas\",\"description\":\"Tramas e personagens\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo192.jpg\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#organizationLogo\",\"width\":192,\"height\":192},\"image\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tevenovelas\",\"https:\\\/\\\/twitter.com\\\/tvnovelas\",\"https:\\\/\\\/www.instagram.com\\\/tvnovelas3\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/author\\\/pauloantoniocaetenews-com-br\\\/#author\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/author\\\/pauloantoniocaetenews-com-br\\\/\",\"name\":\"Paulo Ant\\u00f4nio\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c5bcbd6b5d39e79ed20e5ee737f6db06858bc0fdbc87619a75f2aaad80807e2?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Paulo Ant\\u00f4nio\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#webpage\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/\",\"name\":\"Joia Rara: Quem \\u00e9 quem | Arquivo de Novelas\",\"description\":\"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\\u00edcias e Resumos de novelas\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/joia-rara-quem-e-quem\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/author\\\/pauloantoniocaetenews-com-br\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/author\\\/pauloantoniocaetenews-com-br\\\/#author\"},\"datePublished\":\"2017-02-03T23:24:30-02:00\",\"dateModified\":\"2017-02-04T13:48:05-02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/#website\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/\",\"name\":\"Arquivo de Novelas\",\"description\":\"Tramas e personagens\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Joia Rara: Quem \u00e9 quem | Arquivo de Novelas","description":"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas","canonical_url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#article","name":"Joia Rara: Quem \u00e9 quem | Arquivo de Novelas","headline":"Joia Rara: Quem \u00e9 quem","author":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/author\/pauloantoniocaetenews-com-br\/#author"},"publisher":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.caetenews.com.br\/page\/media\/62\/joiararaqq01.jpg","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#articleImage"},"datePublished":"2017-02-03T23:24:30-02:00","dateModified":"2017-02-04T13:48:05-02:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#webpage"},"isPartOf":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#webpage"},"articleSection":"Blog, Personagens"},{"@type":"BreadcrumbList","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo#listItem","position":1,"name":"Home","item":"https:\/\/tvnovelas.com.br\/page2\/arquivo","nextItem":{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#listItem","name":"Joia Rara: Quem \u00e9 quem"},"previousItem":{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#listItem","position":3,"name":"Joia Rara: Quem \u00e9 quem","previousItem":{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/#organization","name":"TV Novelas","description":"Tramas e personagens","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/","logo":{"@type":"ImageObject","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2020\/11\/logo192.jpg","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#organizationLogo","width":192,"height":192},"image":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/tevenovelas","https:\/\/twitter.com\/tvnovelas","https:\/\/www.instagram.com\/tvnovelas3\/"]},{"@type":"Person","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/author\/pauloantoniocaetenews-com-br\/#author","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/author\/pauloantoniocaetenews-com-br\/","name":"Paulo Ant\u00f4nio","image":{"@type":"ImageObject","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3c5bcbd6b5d39e79ed20e5ee737f6db06858bc0fdbc87619a75f2aaad80807e2?s=96&d=mm&r=g","width":96,"height":96,"caption":"Paulo Ant\u00f4nio"}},{"@type":"WebPage","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#webpage","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/","name":"Joia Rara: Quem \u00e9 quem | Arquivo de Novelas","description":"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/#website"},"breadcrumb":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/#breadcrumblist"},"author":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/author\/pauloantoniocaetenews-com-br\/#author"},"creator":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/author\/pauloantoniocaetenews-com-br\/#author"},"datePublished":"2017-02-03T23:24:30-02:00","dateModified":"2017-02-04T13:48:05-02:00"},{"@type":"WebSite","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/#website","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/","name":"Arquivo de Novelas","description":"Tramas e personagens","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Arquivo de Novelas | Tramas e personagens","og:type":"article","og:title":"Joia Rara: Quem \u00e9 quem | Arquivo de Novelas","og:description":"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas","og:url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/","article:published_time":"2017-02-04T01:24:30+00:00","article:modified_time":"2017-02-04T15:48:05+00:00","article:publisher":"https:\/\/www.facebook.com\/tevenovelas","twitter:card":"summary_large_image","twitter:site":"@tvnovelas","twitter:title":"Joia Rara: Quem \u00e9 quem | Arquivo de Novelas","twitter:description":"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas","twitter:creator":"@tvnovelas"},"aioseo_meta_data":{"post_id":"795","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-07-26 16:01:05","updated":"2025-06-03 22:56:29","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJoia Rara: Quem \u00e9 quem\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo"},{"label":"Blog","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/"},{"label":"Joia Rara: Quem \u00e9 quem","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara-quem-e-quem\/"}],"jetpack_shortlink":"https:\/\/wp.me\/pfspD2-cP","jetpack-related-posts":[{"id":793,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/joia-rara\/","url_meta":{"origin":795,"position":0},"title":"Joia Rara: hist\u00f3ria e personagens","author":"Paulo Ant\u00f4nio","date":"03\/02\/2017","format":false,"excerpt":"Uma hist\u00f3ria de uma paix\u00e3o proibida Joia Rara foi a novela das seis da Globo, a partir de 16 de setembro de 2013. Uma hist\u00f3ria que promete surpreender e emocionar, escrita por Thelma Guedes e Duca Rachid. A trama se passa no Rio de Janeiro entre 1934 e 1945 e\u2026","rel":"","context":"Em &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2613,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/te-dou-a-vida-quem-e-quem\/","url_meta":{"origin":795,"position":1},"title":"&#8216;Te Dou a Vida&#8217; &#8211; Quem \u00e9 Quem","author":"Paulo Ant\u00f4nio","date":"11\/09\/2021","format":false,"excerpt":"Novela Te Dou a Vida: 'Te Dou a Vida' (Te Doy la Vida) \u00e9 uma telenovela mexicana escrita e produzida por Lucero Su\u00e1rez para Televisa e exibida entre mar\u00e7o de julho de 2020. Confira o perfil dos principais personagens: Pedro ((Jos\u00e9 Ron) Pedro \u00e9 um mec\u00e2nico que de uma hora\u2026","rel":"","context":"Em &quot;SBT&quot;","block_context":{"text":"SBT","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/sbt\/"},"img":{"alt_text":"Foto de divulga\u00e7\u00e3o de Te Dou a Vida","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/09\/tedouavida01.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/09\/tedouavida01.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/09\/tedouavida01.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1304,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/um-caminho-para-o-destino\/","url_meta":{"origin":795,"position":2},"title":"\u00b4Um Caminho Para o Destino\u00b4 (Un Camino Hacia el Destino)","author":"Paulo Ant\u00f4nio","date":"26\/08\/2017","format":false,"excerpt":"'Um Caminho Para o Destino' estreou no M\u00e9xico em 2016 (Un Camino Hacia el Destino) e exibida pelo SBT a partir de 28 de agosto de 2017. \u00c9 protagonizada por Paulina Goto e Horacio Pancheri. Os dois interpretam Luisa e Carlos, jovem casal apaixonado que nem imagina o quanto que\u2026","rel":"","context":"Em &quot;SBT&quot;","block_context":{"text":"SBT","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/sbt\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2017\/08\/umcaminhopodestino01.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2632,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/te-dou-a-vida-um-drama-em-familia\/","url_meta":{"origin":795,"position":3},"title":"&#8216;Te Dou a Vida&#8217;: Um drama em fam\u00edlia","author":"Paulo Ant\u00f4nio","date":"14\/09\/2021","format":false,"excerpt":"Estrelada por Jose Ron, Eva Cede\u00f1o e Jorge Salinas, a novela conta a hist\u00f3ria de duas fam\u00edlias que se conhecem por causa de....","rel":"","context":"Em &quot;SBT&quot;","block_context":{"text":"SBT","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/sbt\/"},"img":{"alt_text":"foto de cena de Te Dou a Vida","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/09\/tedouavida02.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/09\/tedouavida02.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/09\/tedouavida02.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":475,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/perola-negra\/","url_meta":{"origin":795,"position":4},"title":"P\u00e9rola Negra","author":"Paulo Ant\u00f4nio","date":"01\/02\/2017","format":false,"excerpt":"A trama da novela de Henrique Zambelli (Baseada em Perla Negra, de Ra\u00fal Lecouna), exibida pelo SBT, narra a hist\u00f3ria de uma mulher misteriosa que abandona uma menina rec\u00e9m-nascida, fruto de um amor proibido, em uma conceituada escola exclusiva para mo\u00e7as. Junto com o beb\u00ea, ela entrega para Miss Helen\u2026","rel":"","context":"Em &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2017\/02\/novela_perolanegra_logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":506,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/araguaia-quem-e-quem\/","url_meta":{"origin":795,"position":5},"title":"Araguaia: Quem \u00e9 quem","author":"Paulo Ant\u00f4nio","date":"01\/02\/2017","format":false,"excerpt":"Principais personagens: A est\u00e2ncia de Antoninha Antoninha (Regina Duarte) - M\u00e3e de Fernando (Edson Celulari) e av\u00f3 de Solano (Murilo Rosa). \u00c9 dona de uma est\u00e2ncia na regi\u00e3o do Araguaia, fundada por seus ancestrais, Antonia (Alice Motta) e Apoena (Diogo Oliveira). Sua fam\u00edlia \u00e9 v\u00edtima de uma maldi\u00e7\u00e3o e por\u2026","rel":"","context":"Em &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts\/795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/comments?post=795"}],"version-history":[{"count":3,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts\/795\/revisions"}],"predecessor-version":[{"id":799,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts\/795\/revisions\/799"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/media?parent=795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/categories?post=795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/tags?post=795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}