{"id":2079,"date":"2019-03-23T16:23:01","date_gmt":"2019-03-23T19:23:01","guid":{"rendered":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/?p=2079"},"modified":"2020-03-30T10:43:12","modified_gmt":"2020-03-30T13:43:12","slug":"kubanacan-republica-de-bananas","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/kubanacan-republica-de-bananas\/","title":{"rendered":"Kubanacan: Rep\u00fablica de Bananas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2019\/03\/novela_kubanacan_logo.jpg\" alt=\"\" width=\"250\" height=\"169\" class=\"alignnone size-full wp-image-2265\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2080 size-full\" title=\" (Foto: TV Globo\/Divulga\u00e7\u00e3o)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2019\/09\/kubanacan01.jpg\" alt=\"Foto do gal. Camacho (Humberto Martins)\" width=\"500\" height=\"300\" \/><br \/>\nKubanacan era uma \u201crep\u00fablica de bananas\u201d, caracterizada por problemas econ\u00f4micos, pol\u00edticos e sociais, como corrup\u00e7\u00e3o, empreguismo, coronelismo e incha\u00e7o da m\u00e1quina p\u00fablica. Qualquer semelhan\u00e7a com o Brasil e outros pa\u00edses da Am\u00e9rica Latina n\u00e3o era mera coincid\u00eancia, afinal a novela era uma s\u00e1tira pol\u00edtica. Esse era o contexto da com\u00e9dia-pastel\u00e3o de Carlos Lombardi, ambientada na d\u00e9cada de 1950, em uma fict\u00edcia ilha caribenha, regi\u00e3o de sol, salsa e muita sensualidade. As confus\u00f5es amorosas da trama ficaram por conta dos personagens Esteban (Marcos Pasquim), Marisol (Danielle Winits), Enrico (Vladimir Brichta), Lola (Adriana Esteves) e Rubi (Carolina Ferraz).<\/p>\n<p>Kubanacan \u00e9 uma rep\u00fablica desde o s\u00e9culo XIX, mas elei\u00e7\u00f5es presidenciais s\u00e3o um fato raro em sua hist\u00f3ria, mais afeita a golpes de Estado. A regi\u00e3o \u00e9 produtora de bananas \u2013 que aparecem na composi\u00e7\u00e3o da maioria dos pratos da ilha \u2013, e todos os outros produtos consumidos pela popula\u00e7\u00e3o s\u00e3o importados. Seu desenvolvimento se restringe \u00e0 capital, La Bendita. O pa\u00eds tem constantes problemas com a ilha vizinha, La Platina, grande produtora de carne bovina. Uma na\u00e7\u00e3o acusa a outra de boicotes e espionagem, e essa rivalidade hist\u00f3rica acaba sempre em guerras que camuflam os reais problemas internos que cada uma enfrenta.<\/p>\n<p>Os militares se acostumaram a ditar as regras do pa\u00eds e n\u00e3o agem de outra forma quando, em 1951, tr\u00eas anos ap\u00f3s a elei\u00e7\u00e3o do professor R\u00fabio Montenegro (St\u00eanio Garcia), come\u00e7am a sentir-se incomodados com a benevol\u00eancia do governo diante dos protestos da oposi\u00e7\u00e3o. Amante da primeira-dama, Mercedes Montenegro (Betty Lago), o general Carlos Pantaleon Camacho (Humberto Martins) antecipa-se ao golpe que estava sendo planejado pelo Ex\u00e9rcito e assume o poder ap\u00f3s a morte de R\u00fabio Montenegro \u2013 o presidente rola a escada depois de uma briga, ap\u00f3s flagrar a mulher com o general. Mercedes \u00e9 considerada santa pelo povo, pela ajuda humanit\u00e1ria que sempre deu aos necessitados.<\/p>\n<p>Carlos Lombardi partiu de tr\u00eas inspira\u00e7\u00f5es para construir a trama de Kubanacan. Como ponto de partida, a novela Que Rei Sou Eu? (1989), de Cassiano Gabus Mendes, ao usar a s\u00e1tira pol\u00edtica como cr\u00edtica aos problemas encontrados nos pa\u00edses do terceiro mundo; a Cuba pr\u00e9-Fidel Castro, para contar a hist\u00f3ria, em tom de com\u00e9dia, de todos os regimes militares de que tinha conhecimento; e o filme A Identidade Bourne (2002), de Doug Liman, que o ajudou a montar o perfil de Esteban (Marcos Pasquim), um desmemoriado. O mapa de Kubanacan era uma adapta\u00e7\u00e3o do mapa da Rep\u00fablica Dominicana.<\/p>\n<p>Autoria: Carlos Lombardi<br \/>\nColabora\u00e7\u00e3o: Emanoel Jacobina, Margareth Boury, Tiago Santiago e Vin\u00edcius Vianna<br \/>\nDire\u00e7\u00e3o: Marco Rodrigo, Cl\u00e1udio Boeckel e Edgard Miranda<br \/>\nDire\u00e7\u00e3o-geral: Wolf Maya, Alexandre Avancini, Roberto Talma<br \/>\nDire\u00e7\u00e3o de n\u00facleo: Wolf Maya, Roberto Talma<br \/>\nPer\u00edodo de exibi\u00e7\u00e3o: 05\/05\/2003 \u2013 24\/01\/2004<br \/>\nHor\u00e1rio: 19h<br \/>\nN\u00ba de cap\u00edtulos: 227<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kubanacan era uma \u201crep\u00fablica de bananas\u201d, caracterizada por problemas econ\u00f4micos, pol\u00edticos e sociais, como corrup\u00e7\u00e3o, empreguismo, coronelismo e incha\u00e7o da&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2081,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[49,55,54,52,56,53],"class_list":["post-2079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-globo","tag-adriana-esteves","tag-carlos-lombardi","tag-humberto-martins","tag-kubanacan","tag-marcos-pasquim","tag-rede-globo","wpcat-2-id"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2019\/09\/kubanacan01-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/pfspD2-xx","jetpack-related-posts":[{"id":2517,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/roda-de-fogo-um-empresario-inescrupuloso\/","url_meta":{"origin":2079,"position":0},"title":"Roda de Fogo: Um empres\u00e1rio inescrupuloso","author":"Paulo Ant\u00f4nio","date":"01\/03\/2020","format":false,"excerpt":"Empres\u00e1rio bem-sucedido e inescrupuloso, Renato Villar (Tarc\u00edsio Meira) mant\u00e9m um casamento de apar\u00eancias com Carolina (Renata Sorrah), uma mulher fria e ambiciosa. Um dossi\u00ea com irregularidades em uma das empresas dele \u00e9 revelado, o que provoca um esc\u00e2ndalo no meio empresarial. A ju\u00edza que assume o caso \u00e9 L\u00facia Brand\u00e3o\u2026","rel":"","context":"Em &quot;Globo&quot;","block_context":{"text":"Globo","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/globo\/"},"img":{"alt_text":"Foto de divulga\u00e7\u00e3o","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/04\/rodadefogo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/04\/rodadefogo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/04\/rodadefogo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1865,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-cravo-e-a-rosa-o-caipira-petruchio-e-a-fera-catarina\/","url_meta":{"origin":2079,"position":1},"title":"O Cravo e a Rosa: O caipira Petruchio e a fera Catarina","author":"Paulo Ant\u00f4nio","date":"19\/03\/2019","format":false,"excerpt":"O Cravo e a Rosa, novela escrita por Walcyr Carrasco e M\u00e1rio Teixeira, com colabora\u00e7\u00e3o de Duca Rachid, produzida pela Rede Globo para exibi\u00e7\u00e3o na faixa das 18 horas, \u00e9 uma com\u00e9dia rom\u00e2ntica inspirada no cl\u00e1ssico A Megera Domada, de William Shakespeare, a novela \u00e9 ambientada na S\u00e3o Paulo dos\u2026","rel":"","context":"Em &quot;Globo&quot;","block_context":{"text":"Globo","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/globo\/"},"img":{"alt_text":"Foto de Catarina e Petruchio se casando","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2019\/03\/ocravoearosa01.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2019\/03\/ocravoearosa01.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2019\/03\/ocravoearosa01.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1600,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/a-indomada\/","url_meta":{"origin":2079,"position":2},"title":"A Indomada: tradi\u00e7\u00f5es brit\u00e2nicas no nordeste","author":"Paulo Ant\u00f4nio","date":"28\/07\/2018","format":false,"excerpt":"'A Indomada' \u00e9 uma novela de Aguinaldo Silva e Ricardo Linhares, produzida pela Globo e exibida entre fevereiro e outubro de 1997, na faixa das 20h. Novela em exibi\u00e7\u00e3o pelo canal Viva a partir de 30 de julho de 2018 A hist\u00f3ria se passa na fict\u00edcia Greenville, cidade do litoral\u2026","rel":"","context":"Em &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2018\/07\/aindomada001.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2070,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/amor-de-mae-em-busca-do-filho-vendido\/","url_meta":{"origin":2079,"position":3},"title":"&#8216;Amor de M\u00e3e&#8217;: A busca pelo filho vendido","author":"Paulo Ant\u00f4nio","date":"23\/09\/2019","format":false,"excerpt":"'Amor de M\u00e3e' conta tr\u00eas m\u00e3es protagonistas: Lurdes (Lucy Alves\/Regina Cas\u00e9), Thelma (Adriana Esteves) e Vit\u00f3ria (Ta\u00eds Araujo). Lurdes (Lucy Alves\/Regina Cas\u00e9) \u00e9 de Malaquitas, cidade fict\u00edcia no Rio Grande do Norte. Deu \u00e0 luz quatro filhos: Magno, Ryan, Dom\u00eanico e \u00c9rica. H\u00e1 26 anos, enquanto Lurdes estava na maternidade\u2026","rel":"","context":"Em &quot;Amor de M\u00e3e&quot;","block_context":{"text":"Amor de M\u00e3e","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/amor-de-mae\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2019\/09\/amordemae2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2019\/09\/amordemae2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2019\/09\/amordemae2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2690,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/renascer-a-historia-de-rejeicao-de-um-pai-pelo-filho\/","url_meta":{"origin":2079,"position":4},"title":"Renascer (1993): A hist\u00f3ria de rejei\u00e7\u00e3o de um pai pelo filho","author":"Paulo Ant\u00f4nio","date":"11\/10\/2021","format":false,"excerpt":"Renascer Ano de Produ\u00e7\u00e3o: 1993 Elenco: Ant\u00f4nio Fagundes, Marcos Palmeira, Adriana Esteves, Patr\u00edcia Pillar, Herson Capri, Jos\u00e9 de Abreu, Luciana Braga, Tarc\u00edsio Filho, Maria Lu\u00edsa Mendon\u00e7a, Marco Ricca, Regina Dourado. Entre lendas, mitologias e regionalismos, \u201cRenascer\u201d conta a hist\u00f3ria de rejei\u00e7\u00e3o de um pai pelo filho, ap\u00f3s a morte da\u2026","rel":"","context":"Em &quot;Globo&quot;","block_context":{"text":"Globo","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/globo\/"},"img":{"alt_text":"foto de Adriana Esteves, em Renascer","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/10\/renascer2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/10\/renascer2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/10\/renascer2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":543,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/morde-assopra\/","url_meta":{"origin":2079,"position":5},"title":"Morde &#038; Assopra","author":"Paulo Ant\u00f4nio","date":"01\/02\/2017","format":false,"excerpt":"Rob\u00f4s, dinossauros, romance e humor Morde & Assopra, a nova novela de Walcyr Carrasco, com dire\u00e7\u00e3o de Rog\u00e9rio Gomes, vai trazer temas inusitados para a telinha: rob\u00f4s, ca\u00e7a aos dinossauros e cultura japonesa s\u00e3o apenas alguns deles. Tudo regado a muito romance e humor. A hist\u00f3ria come\u00e7a no Jap\u00e3o: a\u2026","rel":"","context":"Em &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts\/2079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/comments?post=2079"}],"version-history":[{"count":2,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts\/2079\/revisions"}],"predecessor-version":[{"id":2266,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts\/2079\/revisions\/2266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/media\/2081"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/media?parent=2079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/categories?post=2079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/tags?post=2079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}