{"id":1557,"date":"2018-06-11T10:42:15","date_gmt":"2018-06-11T13:42:15","guid":{"rendered":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/?p=1557"},"modified":"2019-02-21T17:52:27","modified_gmt":"2019-02-21T20:52:27","slug":"o-tempo-nao-para-personagens","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/","title":{"rendered":"O Tempo N\u00e3o Para &#8211; Personagens"},"content":{"rendered":"<p><strong>Marocas (Juliana Paiva)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1559 size-full\" title=\"(Foto: TV Globo\/O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq01.jpg\" alt=\"Foto de Marocas (Juliana Paiva)\" width=\"250\" height=\"142\" \/><br \/>\nDivertida, inteligente, curiosa e corajosa. Apesar de ser uma mo\u00e7a do s\u00e9culo XIX, n\u00e3o tem nada de fr\u00e1gil. \u00c9 filha de Dom Sabino e Agustina, e irm\u00e3 de Nico e Kiki, com quem mora na fazenda Nossa Senhora do \u00d3, situada onde depois foi constru\u00eddo o largo da matriz da Freguesia do \u00d3 e as demais constru\u00e7\u00f5es do bairro. Recebe aulas particulares com a preceptora Miss Celine e conta com a escrava Dam\u00e1sia como dama de companhia. Tem uma rela\u00e7\u00e3o afetuosa com o pai, que sonha em casar a filha com um bom partido. Foi criada por Dom Sabino para ser independente, desde que isso n\u00e3o entre em choque com as conven\u00e7\u00f5es da \u00e9poca. Vai se adaptar rapidamente ao s\u00e9culo XXI, exceto no que se refere ao amor. Contudo, mais do que se readaptar, ela ter\u00e1 que reaprender a sentir.<\/p>\n<p><strong>Bar\u00e3o (Rui Ricardo Diaz)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1560 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq02.jpg\" alt=\"Foto de Bar\u00e3o (Rui Ricardo Diaz)\" width=\"250\" height=\"142\" \/><br \/>\n\u00c9 o l\u00edder do crime na Zona Norte. Filho de Eliseu, irm\u00e3o de Lal\u00e1 e pai de Omar e Paulina, que \u00e9 criada pelo av\u00f4. Ainda ama Maz\u00e9, que n\u00e3o quer nem ouvir falar em seu nome.<\/p>\n<p><strong>Bento (Bruno Montaleone)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1561 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq03.jpg\" alt=\"Foto de Bento (Bruno Montaleone)\" width=\"250\" height=\"142\" \/><br \/>\nRec\u00e9m-formado na Faculdade de Direito, faz pose de poeta rebelde e revolucion\u00e1rio, quando na verdade \u00e9 virgem e inexperiente. Acredita que esteja apaixonado por Marocas. Em 2018, vai se interessar pela doutora Helen.<\/p>\n<p><strong>Betina (Cleo Pires)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1562 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq04.jpg\" alt=\"Foto de Betina (Cleo Pires)\" width=\"250\" height=\"142\" \/><br \/>\nNoiva de Samuel. Bonita, forte, independente, \u00e9 a terceira s\u00f3cia na SamVita. Sempre coloca a raz\u00e3o acima da emo\u00e7\u00e3o, menos quando se trata do noivo. Logo percebe o interesse de Samuca por Marocas e n\u00e3o vai aceitar perd\u00ea-lo para a \u201cBela Adormecida\u201d, como a chama. Vai se aproximar de Em\u00edlio a fim de conseguir um aliado para alcan\u00e7ar seus objetivos.<\/p>\n<p><strong>Cairu (Cris Vianna)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1563 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq05.jpg\" alt=\"Foto de Cairu (Cris Vianna)\" width=\"250\" height=\"142\" \/><br \/>\nLinda escrava Mina (escravos que eram cobi\u00e7ados por sua beleza e desenvoltura). Tem o temperamento forte.<\/p>\n<p><strong>Carmen (Christiane Torloni)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1564 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq06.jpg\" alt=\"Foto de Carmen (Christiane Torloni)\" width=\"250\" height=\"142\" \/><br \/>\nM\u00e3e de Samuca, o criou sozinha desde que o marido a abandonou. Vendeu o antigo carro da fam\u00edlia para ajudar o filho a desenvolver o adubo Vitae. Inteligente, independente e cheia de energia, \u00e9 uma das s\u00f3cias da SamVita. Vai virar a cabe\u00e7a de Dom Sabino, que nunca viu uma mulher como ela. Tem um relacionamento com seu personal trainer Lal\u00e1, que na verdade s\u00f3 pensa em se dar bem \u00e0s custas dela por causa de seu poder financeiro e da influ\u00eancia na SamVita.<\/p>\n<p><strong>Cec\u00edlio (Maicon Rodrigues)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1565 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq07.jpg\" alt=\"Foto de Cec\u00edlio (Maicon Rodrigues)\" width=\"250\" height=\"142\" \/><br \/>\nUm tigre (escravo encarregado de limpar as latrinas da casa). Tem o torso marcado pelos dejetos que transporta, por isso o apelido. As marcas em sua pele s\u00e3o parte fundamental para os estudos que Doutora Petra encabe\u00e7a para reconhecer que os \u201ccongelados\u201d s\u00e3o, de fato, de outro s\u00e9culo.<\/p>\n<p><strong>Ces\u00e1ria (Ol\u00edvia Ara\u00fajo)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1566 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq08.jpg\" alt=\"Foto de Ces\u00e1ria (Ol\u00edvia Ara\u00fajo)\" width=\"250\" height=\"142\" \/><br \/>\nAma de leite das crian\u00e7as da fam\u00edlia Sabino Machado. Sempre fica do lado de Marocas. \u00c9 mandona e brava. Ainda no s\u00e9culo XIX, junta uma fortuna com as joias de crioula para comprar sua alforria, mas o ba\u00fa afunda junto com o navio Albatroz. Quando desperta, s\u00f3 quer saber de encontrar suas joias.<\/p>\n<p><strong>Coronela (Solange Couto)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1567 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq09.jpg\" alt=\"Foto de Coronela (Solange Couto)\" width=\"250\" height=\"142\" \/><br \/>\nM\u00e3e de Waleska, \u00e9 mais conhecida como Coronela, j\u00e1 que \u201cherdou\u201d o t\u00edtulo do finado marido. \u00c9 avarenta e fofoqueira mor da Freguesia do \u00d3, e, por causa de sua l\u00edngua afiada, \u00e9 temida por todos. Dona da pens\u00e3o do Largo da Matriz. Mora em um sobrado com a filha, ao lado da pens\u00e3o. Ser\u00e1 capaz de construir um puxadinho para abrigar \u201cos congelados\u201d em sua pens\u00e3o e far\u00e1 de tudo para ter a confian\u00e7a deles. Vai tentar conquistar Te\u00f3filo de qualquer maneira.<\/p>\n<p><strong>Dam\u00e1sia (Aline Dias)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1568 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq10.jpg\" alt=\"Foto de Dam\u00e1sia (Aline Dias)\" width=\"250\" height=\"142\" \/><br \/>\nDama de companhia de Marocas. Escrava do lar, criada na casa-grande. Dam\u00e1sia \u00e9 t\u00edmida e morre de medo de tudo e todos. Apesar disso, est\u00e1 sempre ao lado da sinh\u00e1, mesmo quando ela enfrenta as tradi\u00e7\u00f5es do s\u00e9culo XIX.<\/p>\n<p><strong>Dom Sabino (Edson Celulari)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1569 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq11.jpg\" alt=\"Foto: Dom Sabino (Edson Celulari)\" width=\"250\" height=\"142\" \/><br \/>\nEmpres\u00e1rio vitorioso do Brasil Imperial, \u00e9 descendente de bandeirantes, um homem \u00edntegro e zeloso. Marido de Dona Agustina, pai de Marocas, Nico e Kiki. Trata os escravos e os agregados com respeito. \u00c9 um homem de opini\u00e3o que preza pelo bem-estar dos seus acima de tudo. Considera-se um fiel s\u00fadito da monarquia e sonha com um t\u00edtulo da nobreza. Muitas vezes quer fazer justi\u00e7a com as pr\u00f3prias m\u00e3os, especialmente se for para limpar a honra da fam\u00edlia. Por vezes tem tiradas engra\u00e7adas. Sentir\u00e1 dificuldade em se adaptar ao s\u00e9culo XXI, especialmente diante das novas tecnologias e da \u00e9tica contempor\u00e2nea. Vai ficar encantado pela beleza e autonomia de Carmen e contar\u00e1 com a amizade de Eliseu.<\/p>\n<p><strong>Dona Agustina (Rosi Campos)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1570 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq12.jpg\" alt=\"Foto de Dona Agustina (Rosi Campos)\" width=\"250\" height=\"142\" \/><br \/>\nUma cr\u00e9dula dona de casa e m\u00e3e de fam\u00edlia do s\u00e9culo XIX. \u00c9 esposa de Dom Sabino e m\u00e3e de Marocas, Nico e Kiki. Cr\u00ea em Deus e nos mist\u00e9rios da f\u00e9. Leva a fam\u00edlia, principalmente o marido, com m\u00e3o de ferro. Ter\u00e1 grande resist\u00eancia em aceitar os novos modos do s\u00e9culo XXI, especialmente no que diz respeito \u00e0s mulheres independentes e bem-resolvidas. Vai morrer de ci\u00fames do marido com Carmen.<\/p>\n<p><strong>Eliseu (Milton Gon\u00e7alves)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1571 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq13.jpg\" alt=\"Foto de Eliseu (Milton Gon\u00e7alves)\" width=\"250\" height=\"142\" \/><br \/>\nHonesto e batalhador, \u00e9 realista e pr\u00e1tico, mas jamais perde a esperan\u00e7a. Catador de material recicl\u00e1vel, ele puxa uma carro\u00e7a pelas ruas, de onde tira o seu sustento. Orgulha-se muito de suas origens, mas tem uma grande decep\u00e7\u00e3o com o filho primog\u00eanito, Bar\u00e3o, que entrou para a vida do crime, e o ca\u00e7ula Lal\u00e1, que tamb\u00e9m n\u00e3o se esfor\u00e7a para crescer na vida de maneira honrada. Cuida e trata de Paulina, filha de Bar\u00e3o, como se fosse sua pr\u00f3pria filha, j\u00e1 que n\u00e3o quer ver a neta envolvida na vida marginal que o pai leva. Ser\u00e1 o grande e inesperado amigo de Dom Sabino no s\u00e9culo XXI.<\/p>\n<p><strong>Elmo (Felipe Simas)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1572 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq14.jpg\" alt=\"Foto de Elmo (Felipe Simas)\" width=\"250\" height=\"142\" \/><br \/>\nMelhor amigo e fiel escudeiro de Samuca. Apesar de ter um cora\u00e7\u00e3o de ouro e boas inten\u00e7\u00f5es, \u00e9 um pouco acomodado e mora de favor h\u00e1 anos na cobertura do amigo. Sempre apoiado por Samuca, j\u00e1 se aventurou profissionalmente em diversas \u00e1reas, mas nunca teve \u00eaxito. Agora, receber\u00e1 a chance de ser o gerente do restaurante da SamVita e decidir\u00e1 se mudar para a pens\u00e3o da Coronela. Ama a tenente-coronel Waleska Tib\u00e9rio, que n\u00e3o assume o relacionamento por ter vergonha de ele n\u00e3o ter uma profiss\u00e3o. Ao conhecer Miss Celine, se apaixonar\u00e1 por ela e ficar\u00e1 dividido entre os sentimentos pela oficial e pela preceptora.<\/p>\n<p><strong>Em\u00edlio (Jo\u00e3o Baldasserini)<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1573 size-full\" title=\"(Foto: TV Globo\/ O Tempo N\u00e3o Para)\" src=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/sites\/3\/2018\/07\/otemponaoparaqq15.jpg\" alt=\"Foto de Em\u00edlio (Jo\u00e3o Baldasserini)\" width=\"250\" height=\"142\" \/><br \/>\nAdvogado, s\u00f3cio majorit\u00e1rio do escrit\u00f3rio Ingl\u00eas de Souza Advogados Associados. \u00c9 um vil\u00e3o da trama: ambicioso, sedutor e dissimulado. Tem uma rela\u00e7\u00e3o profissional e amorosa \u201cn\u00e3o assumida\u201d com a advogada Mariacarla, sua s\u00f3cia. Vai se aproximar dos \u201ccongelados\u201d para provar a identidade deles e recuperar suas terras, j\u00e1 sonhando com os bons honor\u00e1rios que isso pode lhe render. Al\u00e9m disso, quer conquistar Marocas e casar com ela para garantir uma boa fortuna.<\/p>\n<p>Helen (Rafaela Mandelli)<br \/>\nJanuza (Bia Montez)<br \/>\nKiki (Nathalia Gon\u00e7alves)<br \/>\nLal\u00e1 (Micael Borges)<br \/>\nLucas (Fhelipe Gomes)<br \/>\nMarciana (Cyria Coentro)<br \/>\nMariacarla (Regiane Alves)<br \/>\nMarino (Marcos Pasquim)<br \/>\nMateus (Raphael Vianna)<br \/>\nMaz\u00e9 (Juliana Alves)<br \/>\nMenelau (David Junior)<br \/>\nMiss Celine (Maria Eduarda de Carvalho)<br \/>\nMonalisa (Alexandra Richter)<br \/>\nNat\u00e1lia (Malu Falangola)<br \/>\nNico (Raphaela Alvittos)<br \/>\nOmar (Max Lima)<br \/>\nPaulina (Carol Macedo)<br \/>\nPedro Parede (Wagner Santisteban)<br \/>\nSamuca (Nicolas Prattes)<br \/>\nTe\u00f3filo (Kiko Mascarenhas)<br \/>\nVanda (Lucy Ramos)<br \/>\nVera L\u00facia (Talita Younan)<br \/>\nWaleska (Carol Castro)<br \/>\nZelda Larocque (Adriane Galisteu)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marocas (Juliana Paiva) Divertida, inteligente, curiosa e corajosa. Apesar de ser uma mo\u00e7a do s\u00e9culo XIX, n\u00e3o tem nada de fr\u00e1gil. \u00c9 filha de Dom Sabino e Agustina, e irm\u00e3 de Nico e Kiki, com quem mora na fazenda Nossa Senhora do \u00d3, situada onde depois foi constru\u00eddo o largo da matriz da Freguesia do &#8230; <a title=\"O Tempo N\u00e3o Para &#8211; Personagens\" class=\"read-more\" href=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/\" aria-label=\"More on O Tempo N\u00e3o Para &#8211; Personagens\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":1559,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,2],"tags":[11,9],"class_list":["post-1557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-globo","tag-globo","tag-personagens"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Paulo Ant\u00f4nio\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Arquivo de Novelas | Tramas e personagens\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"O Tempo N\u00e3o Para \u2013 Personagens | Arquivo de Novelas\" \/>\n\t\t<meta property=\"og:description\" content=\"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-06-11T13:42:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-02-21T20:52:27+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tevenovelas\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@tvnovelas\" \/>\n\t\t<meta name=\"twitter:title\" content=\"O Tempo N\u00e3o Para \u2013 Personagens | Arquivo de Novelas\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@tvnovelas\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#article\",\"name\":\"O Tempo N\\u00e3o Para \\u2013 Personagens | Arquivo de Novelas\",\"headline\":\"O Tempo N\\u00e3o Para &#8211; Personagens\",\"author\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/author\\\/pauloantoniocaetenews-com-br\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/otemponaoparaqq01.jpg\",\"width\":250,\"height\":142},\"datePublished\":\"2018-06-11T10:42:15-03:00\",\"dateModified\":\"2019-02-21T17:52:27-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#webpage\"},\"articleSection\":\"Blog, Globo, Globo, Personagens\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#listItem\",\"name\":\"O Tempo N\\u00e3o Para &#8211; Personagens\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#listItem\",\"position\":3,\"name\":\"O Tempo N\\u00e3o Para &#8211; Personagens\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/#organization\",\"name\":\"TV Novelas\",\"description\":\"Tramas e personagens\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo192.jpg\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#organizationLogo\",\"width\":192,\"height\":192},\"image\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tevenovelas\",\"https:\\\/\\\/twitter.com\\\/tvnovelas\",\"https:\\\/\\\/www.instagram.com\\\/tvnovelas3\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/author\\\/pauloantoniocaetenews-com-br\\\/#author\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/author\\\/pauloantoniocaetenews-com-br\\\/\",\"name\":\"Paulo Ant\\u00f4nio\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c5bcbd6b5d39e79ed20e5ee737f6db06858bc0fdbc87619a75f2aaad80807e2?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Paulo Ant\\u00f4nio\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#webpage\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/\",\"name\":\"O Tempo N\\u00e3o Para \\u2013 Personagens | Arquivo de Novelas\",\"description\":\"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\\u00edcias e Resumos de novelas\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/author\\\/pauloantoniocaetenews-com-br\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/author\\\/pauloantoniocaetenews-com-br\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/otemponaoparaqq01.jpg\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#mainImage\",\"width\":250,\"height\":142},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/o-tempo-nao-para-personagens\\\/#mainImage\"},\"datePublished\":\"2018-06-11T10:42:15-03:00\",\"dateModified\":\"2019-02-21T17:52:27-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/#website\",\"url\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/\",\"name\":\"Arquivo de Novelas\",\"description\":\"Tramas e personagens\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/tvnovelas.com.br\\\/page2\\\/arquivo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"O Tempo N\u00e3o Para \u2013 Personagens | Arquivo de Novelas","description":"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas","canonical_url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#article","name":"O Tempo N\u00e3o Para \u2013 Personagens | Arquivo de Novelas","headline":"O Tempo N\u00e3o Para &#8211; Personagens","author":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/author\/pauloantoniocaetenews-com-br\/#author"},"publisher":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2018\/07\/otemponaoparaqq01.jpg","width":250,"height":142},"datePublished":"2018-06-11T10:42:15-03:00","dateModified":"2019-02-21T17:52:27-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#webpage"},"isPartOf":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#webpage"},"articleSection":"Blog, Globo, Globo, Personagens"},{"@type":"BreadcrumbList","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo#listItem","position":1,"name":"Home","item":"https:\/\/tvnovelas.com.br\/page2\/arquivo","nextItem":{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#listItem","name":"O Tempo N\u00e3o Para &#8211; Personagens"},"previousItem":{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#listItem","position":3,"name":"O Tempo N\u00e3o Para &#8211; Personagens","previousItem":{"@type":"ListItem","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/#organization","name":"TV Novelas","description":"Tramas e personagens","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/","logo":{"@type":"ImageObject","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2020\/11\/logo192.jpg","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#organizationLogo","width":192,"height":192},"image":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/tevenovelas","https:\/\/twitter.com\/tvnovelas","https:\/\/www.instagram.com\/tvnovelas3\/"]},{"@type":"Person","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/author\/pauloantoniocaetenews-com-br\/#author","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/author\/pauloantoniocaetenews-com-br\/","name":"Paulo Ant\u00f4nio","image":{"@type":"ImageObject","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3c5bcbd6b5d39e79ed20e5ee737f6db06858bc0fdbc87619a75f2aaad80807e2?s=96&d=mm&r=g","width":96,"height":96,"caption":"Paulo Ant\u00f4nio"}},{"@type":"WebPage","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#webpage","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/","name":"O Tempo N\u00e3o Para \u2013 Personagens | Arquivo de Novelas","description":"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/#website"},"breadcrumb":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#breadcrumblist"},"author":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/author\/pauloantoniocaetenews-com-br\/#author"},"creator":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/author\/pauloantoniocaetenews-com-br\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2018\/07\/otemponaoparaqq01.jpg","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#mainImage","width":250,"height":142},"primaryImageOfPage":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/#mainImage"},"datePublished":"2018-06-11T10:42:15-03:00","dateModified":"2019-02-21T17:52:27-03:00"},{"@type":"WebSite","@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/#website","url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/","name":"Arquivo de Novelas","description":"Tramas e personagens","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Arquivo de Novelas | Tramas e personagens","og:type":"article","og:title":"O Tempo N\u00e3o Para \u2013 Personagens | Arquivo de Novelas","og:description":"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas","og:url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/","article:published_time":"2018-06-11T13:42:15+00:00","article:modified_time":"2019-02-21T20:52:27+00:00","article:publisher":"https:\/\/www.facebook.com\/tevenovelas","twitter:card":"summary_large_image","twitter:site":"@tvnovelas","twitter:title":"O Tempo N\u00e3o Para \u2013 Personagens | Arquivo de Novelas","twitter:description":"Arquivo de novelas da Globo, SBT, Record, Band, com sinopses e principais personagens. Not\u00edcias e Resumos de novelas","twitter:creator":"@tvnovelas"},"aioseo_meta_data":{"post_id":"1557","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-07-26 16:14:24","updated":"2025-06-03 23:21:40","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tO Tempo N\u00e3o Para \u2013 Personagens\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo"},{"label":"Blog","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/"},{"label":"O Tempo N\u00e3o Para &#8211; Personagens","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-personagens\/"}],"jetpack_shortlink":"https:\/\/wp.me\/pfspD2-p7","jetpack-related-posts":[{"id":1517,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/o-tempo-nao-para-uma-familia-descongelada-132-anos-depois\/","url_meta":{"origin":1557,"position":0},"title":"&#8216;O Tempo N\u00e3o Para&#8217;: uma fam\u00edlia descongelada 132 anos depois","author":"Paulo Ant\u00f4nio","date":"11\/06\/2018","format":false,"excerpt":"Mais de um s\u00e9culo alheios \u00e0s revolu\u00e7\u00f5es sociais, inova\u00e7\u00f5es tecnol\u00f3gicas e conquistas cient\u00edficas. Mais de dez d\u00e9cadas sem sequer ter ouvido falar das guerras mundiais, da chegada do homem \u00e0 lua, da constru\u00e7\u00e3o de avi\u00f5es, do surgimento da internet ou da inven\u00e7\u00e3o da penicilina. S\u00e3o anos de avan\u00e7os e descobertas\u2026","rel":"","context":"Em &quot;Globo&quot;","block_context":{"text":"Globo","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/globo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2018\/06\/otemponaopara01.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1181,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/novo-mundo-como-tudo-comecou\/","url_meta":{"origin":1557,"position":1},"title":"Novo Mundo: Como tudo come\u00e7ou&#8230;","author":"Paulo Ant\u00f4nio","date":"23\/02\/2017","format":false,"excerpt":"Novo Mundo, novela das seis da Globo em exibi\u00e7\u00e3o a partir de mar\u00e7o, retrata a constru\u00e7\u00e3o do novo pa\u00eds que acabou formando o Brasil de hoje. Ali, o p\u00fablico poder\u00e1 ver como foi constru\u00eddo o famoso jeitinho brasileiro, no que resultaram as influ\u00eancias europeias, africanas e ind\u00edgenas, a mistura de\u2026","rel":"","context":"Em &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2017\/02\/novomundo01.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1464,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/belissima-a-obsessao-pelo-poder\/","url_meta":{"origin":1557,"position":2},"title":"Bel\u00edssima: a obsess\u00e3o pelo poder","author":"Paulo Ant\u00f4nio","date":"23\/05\/2018","format":false,"excerpt":"Em Bel\u00edssima, o autor Silvio de Abreu lan\u00e7ou m\u00e3o de uma trama de a\u00e7\u00e3o e mist\u00e9rio para falar sobre a import\u00e2ncia da imagem em uma sociedade regida pelas apar\u00eancias, discutindo valores como beleza, sucesso e honestidade. A novela \u00e9 ambientada em S\u00e3o Paulo. A hist\u00f3ria come\u00e7a na Gr\u00e9cia, quando Pedro\u2026","rel":"","context":"Em &quot;Globo&quot;","block_context":{"text":"Globo","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/globo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2018\/05\/belissima01.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2572,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/nos-tempos-do-imperador-d-pedro-ii-a-familia-imperial-e-a-condessa-de-barral\/","url_meta":{"origin":1557,"position":3},"title":"\u2018Nos Tempos do Imperador\u2019:  D. Pedro II, a Fam\u00edlia Imperial e a Condessa de Barral","author":"Paulo Ant\u00f4nio","date":"07\/07\/2021","format":false,"excerpt":"Mais de 30 anos se passaram ap\u00f3s a Proclama\u00e7\u00e3o da Independ\u00eancia. O pa\u00eds em constru\u00e7\u00e3o, come\u00e7a a dar lugar a um Brasil em busca de identidade e progresso em \u2018Nos Tempos do Imperador\u2019, nova novela das seis, escrita e criada por Alessandro Marson e Thereza Falc\u00e3o, e com dire\u00e7\u00e3o art\u00edstica\u2026","rel":"","context":"Em &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/07\/29464.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/07\/29464.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2021\/07\/29464.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1434,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/orgulho-e-paixao\/","url_meta":{"origin":1557,"position":4},"title":"Orgulho e Paix\u00e3o: Paix\u00f5es, aventuras e humor","author":"Paulo Ant\u00f4nio","date":"15\/02\/2018","format":false,"excerpt":"Escrita por Marcos Bernstein, com dire\u00e7\u00e3o art\u00edstica de Fred Mayrink, 'Orgulho e Paix\u00e3o', pr\u00f3xima novela da 6, da Rede Globo, \u00e9 inspirada nos romances da escritora inglesa Jane Austen. A nova novela, das 6, com estreia em mar\u00e7o de 2018, traz uma narrativa leve e descontra\u00edda sobre os encontros e\u2026","rel":"","context":"Em &quot;Globo&quot;","block_context":{"text":"Globo","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/globo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2018\/02\/orgulhoepaixao01.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":262,"url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/pantanal\/","url_meta":{"origin":1557,"position":5},"title":"Pantanal: Uma hist\u00f3ria de amor e vida no para\u00edso ecol\u00f3gico","author":"Paulo Ant\u00f4nio","date":"29\/01\/2017","format":false,"excerpt":"Uma marca da teledramaturgia brasileira A trama conta a hist\u00f3ria de um casal de posseiros que chega ao Pantanal \u00e0 procura de \"uma terra que n\u00e3o tenha tantos donos\". Maria Marru\u00e1 (C\u00e1ssia Kiss) e Z\u00e9 (Jos\u00e9 Dummont), depois de muito sofrerem com a perda de todos os seus filhos em\u2026","rel":"","context":"Em &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/category\/blog\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-content\/uploads\/2018\/07\/otemponaoparaqq01.jpg","_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts\/1557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/comments?post=1557"}],"version-history":[{"count":2,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts\/1557\/revisions"}],"predecessor-version":[{"id":1574,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/posts\/1557\/revisions\/1574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/media\/1559"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/media?parent=1557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/categories?post=1557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/page2\/arquivo\/wp-json\/wp\/v2\/tags?post=1557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}