{"id":9368,"date":"2021-11-27T12:19:51","date_gmt":"2021-11-27T15:19:51","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=9368"},"modified":"2021-11-27T13:24:31","modified_gmt":"2021-11-27T16:24:31","slug":"o-que-e-o-verme-gigante-de-duna","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/o-que-e-o-verme-gigante-de-duna\/","title":{"rendered":"O que \u00e9 o verme gigante de &#8216;Duna&#8217;?"},"content":{"rendered":"<p><em>Not\u00edcias de cinema: Duna:<\/em><br \/>\n<img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/11\/duna3.jpg?resize=600%2C338&#038;ssl=1\" alt=\"Duna\" width=\"600\" height=\"338\" class=\"alignnone size-full wp-image-9369\" \/><br \/>\nSe voc\u00ea ainda n\u00e3o assistiu a \u201cDuna\u201d, com certeza viu algum trailer ou an\u00fancio e ficou com uma d\u00favida na cabe\u00e7a: \u201co que \u00e9 esse verme gigante?!\u201d. Para os que n\u00e3o est\u00e3o familiarizados com o filme e nem com a s\u00e9rie de livros, aquela estranha criatura colossal traz curiosidade e uma s\u00e9rie de perguntas consigo. O que ela \u00e9? Qual seu papel no universo de Duna? Saiba tudo sobre ele para  poder assistir ao filme preparado!<\/p>\n<p>Os Vermes da Areia habitam o planeta Arrakis, que, por causa de seu clima des\u00e9rtico, tamb\u00e9m \u00e9 conhecido como (adivinha?) Duna. Al\u00e9m de seu tamanho aterrador, os Vermes atacam tudo o que se mexe sobre a superf\u00edcie, tornando qualquer visita a Arrakis uma tarefa de vida ou morte. E os perigos do planeta n\u00e3o terminam por a\u00ed! O clima \u00e1rido e escassez de \u00e1gua obrigam seus habitantes a vestirem trajes de sobreviv\u00eancia especiais, que reutilizam ao m\u00e1ximo os l\u00edquidos do pr\u00f3prio corpo para mant\u00ea-los hidratados.<\/p>\n<p>Vermes carn\u00edvoros gigantes, escassez geral de \u00e1gua, \u00e1ridos mares de areia\u2026 Os perigos de Arrakis parecem ser suficientes para manter qualquer viajante interplanet\u00e1rio bem longe de seu solo.<\/p>\n<p>H\u00e1 uma raz\u00e3o que torna Arrakis um ponto de interesse de todo o universo. L\u00e1 \u00e9 o \u00fanico lugar onde \u00e9 encontrada a especiaria M\u00e9lange, uma subst\u00e2ncia capaz de aumentar a percep\u00e7\u00e3o do usu\u00e1rio e permitir que pilotos de naves espaciais tenham a aten\u00e7\u00e3o e os reflexos necess\u00e1rios para cruzar dist\u00e2ncias intergal\u00e1cticas em uma velocidade imensur\u00e1vel. M\u00e9lange \u00e9 um dos bens mais preciosos de todo o cosmos.<\/p>\n<p>\u00c9 aqui que entra a grande import\u00e2ncia dos Vermes da Areia em \u201cDuna\u201d: s\u00e3o eles mesmos quem produzem o M\u00e9lange.<\/p>\n<p>Quer saber como essa hist\u00f3ria vai se desenrolar? \u201cDuna\u201d j\u00e1 est\u00e1 dispon\u00edvel nas principais plataformas digitais e voc\u00ea pode escolher onde assistir clicando no seu t\u00edtulo em destaque!<\/p>\n<h3>Duna<\/h3>\n<p>Fic\u00e7\u00e3o<br \/>\n<strong>Estreia: 21\/10\/2021<\/strong><br \/>\n Diretor: Denis Villeneuve<br \/>\nElenco: Timoth\u00e9e Chalamet, Oscar Isaac, Rebecca Ferguson<br \/>\nClassifica\u00e7\u00e3o: 14 Anos<br \/>\n<em>Sinopse<\/em><br \/>\nEm um futuro distante, planetas s\u00e3o comandados por casas nobres que fazem parte de um imp\u00e9rio feudal intergal\u00e1tico. Paul Atreides (Timoth\u00e9e Chalamet) \u00e9 um jovem cuja fam\u00edlia toma controle do planeta deserto Arrakis, tamb\u00e9m conhecido como Duna. Sendo a \u00fanica fonte da especiaria melange, a subst\u00e2ncia mais importante do cosmos, Arrakis se prova ser um planeta nem um pouco f\u00e1cil de governar. Classifica\u00e7\u00e3o indicativa 14 anos, cont\u00e9m viol\u00eancia.<br \/>\n<iframe width=\"728\" height=\"410\" src=\"https:\/\/www.youtube.com\/embed\/pBYsSos0xhY\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3>\u00daltimas not\u00edcias:<\/p>\n<h3>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-6bd8abdjeq\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/temporada-3-de-euphoria-estreia-domingo-dia-12-4-na-hbo-max\/\" class=\"_blank\" target=\"_blank\" >Temporada 3 de Euphoria estreia domingo, dia 12\/4, na HBO Max<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-netflix-estreia-live-action-de-cavaleiros-do-zodiaco\/\" class=\"_blank\" target=\"_blank\" >A Netflix estreia live-action de Cavaleiros do Zod\u00edaco<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/minha-fera-estreia-no-globoplay-neste-sabado-28-de-marco\/\" class=\"_blank\" target=\"_blank\" >&#8220;Minha Fera&#8221; estreia no Globoplay neste s\u00e1bado, 28 de mar\u00e7o<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/supergirl-chega-aos-cinemas-em-junho\/\" class=\"_blank\" target=\"_blank\" >Supergirl chega aos cinemas em junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-os-casos-de-harry-hole-estreia-na-netflix-nesta-quinta-dia-26\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie &#8216;Os casos de Harry Hole&#8217; estreia na Netflix nesta quinta, dia 26<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/chamas-do-destino-cicek-abre-mao-de-fortuna-para-ficar-com-atlas\/\" class=\"_blank\" target=\"_blank\" >Chamas do Destino:  Cicek abre m\u00e3o de fortuna para ficar com Atlas<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/bridgerton-4at-parte-2-chega-nesta-quinta-26-na-netflix\/\" class=\"_blank\" target=\"_blank\" >Bridgerton (4\u00aaT), parte 2 chega nesta quinta (26), na Netflix<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/programacao-de-filmes-na-tv-para-o-fim-de-semana\/\" class=\"_blank\" target=\"_blank\" >Programa\u00e7\u00e3o de filmes na TV para o fim de semana<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-aniela-chega-na-netflix-dia-11-de-junho\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie Aniela chega na Netflix dia 11 de junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-idade-dourada-t3-estreia-no-max-dia-21-de-junho\/\" class=\"_blank\" target=\"_blank\" >A Idade Dourada (T3) estreia no Max em 21 de junho<\/a><\/h4><\/div><\/div><\/div><\/div><\/div><\/p>\n<h3>Saiba mais<\/h3>\n<p><a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/filmes-e-series-que-estreiam-na-netflix-em-dezembro-21\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias de in\u00e9ditos na Netflix no m\u00eas de dezembro\/2021<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/filmes-e-series-ineditos-em-estreia-na-semana-na-netflix\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias da semana na Netflix<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/o-que-ha-de-novo-no-globoplay\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias e novidades no Globoplay<\/strong><\/a><br \/>\n<a href=\"\/\/tvnovelas.com.br\/filmes\/filmes-em-estreia-nos-cinemas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias e novidades no Cinema<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.tvnovelas.com.br\/novelas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Resumos de novelas<\/strong><\/a><br \/>\n<a href=\"https:\/\/caetenews.com.br\/semana\/filmes-da-globo-na-sessao-da-tarde-desta-semana\/\" rel=\"noopener\" target=\"_blank\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se voc\u00ea ainda n\u00e3o assistiu a \u201cDuna\u201d, com certeza viu algum trailer ou an\u00fancio e ficou com uma d\u00favida na cabe\u00e7a: \u201co que \u00e9 esse verme gigante?!\u201d. Para os que n\u00e3o est\u00e3o familiarizados com o filme e nem&#8230;<\/p>\n","protected":false},"author":1,"featured_media":9369,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[663],"tags":[675],"class_list":["post-9368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-warnerbros","tag-duna","wpcat-663-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/11\/duna3.jpg?fit=600%2C338&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-2r6","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/9368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=9368"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/9368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/9369"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=9368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=9368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=9368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}