{"id":9341,"date":"2021-11-26T18:00:12","date_gmt":"2021-11-26T21:00:12","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=9341"},"modified":"2021-11-26T12:46:27","modified_gmt":"2021-11-26T15:46:27","slug":"tres-filmes-de-natal-sao-novidades-no-telecine-neste-sabado-27","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/tres-filmes-de-natal-sao-novidades-no-telecine-neste-sabado-27\/","title":{"rendered":"Tr\u00eas filmes de Natal s\u00e3o novidades no Telecine neste s\u00e1bado, 27"},"content":{"rendered":"<p><em>Not\u00edcias do Telecine:<\/em><\/p>\n<h3>Um Natal Cinco Estrelas<\/h3>\n<p>Five Star Christmas<br \/>\n<img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/11\/umnatalcincostars-1.jpg?resize=587%2C360&#038;ssl=1\" alt=\"Foto de Um Natal Cinco Estrelas, em Telecine\" width=\"587\" height=\"360\" class=\"alignnone size-full wp-image-9342\" \/><br \/>\n<strong>Dispon\u00edvel a partir de 27\/11 &#8211; 00h<\/strong><br \/>\nCom\u00e9dia, Com\u00e9dia Rom\u00e2ntica<br \/>\nEUA &#8211; 2020<br \/>\nDire\u00e7\u00e3o: Christie Will Wolf<br \/>\nElenco: Bethany Joy Lenz, Victor Webster, Robert Wisden<br \/>\nO cr\u00edtico Jake (Victor Webster) aparece de surpresa na hospedaria da fam\u00edlia Ralson. Preocupados com a poss\u00edvel cr\u00edtica publicada, os familiares se passam por h\u00f3spedes com o intuito de tecerem coment\u00e1rios positivos sobre o hotel. No entanto, as coisas se complicam quando a filha Lucy (Bethany Joy Lenz) se apaixona pelo escritor.<\/p>\n<h3>O Natal dos Darlingtons<\/h3>\n<p>Christmas With The Darling<br \/>\n<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/11\/onataldosdarling-1.jpg?resize=600%2C360&#038;ssl=1\" alt=\"Foto de O Natal dos Darlingtons, em Telecine\" width=\"600\" height=\"360\" class=\"alignnone size-full wp-image-9343\" \/><br \/>\nCom\u00e9dia, Com\u00e9dia Fam\u00edlia<br \/>\n<strong>Dispon\u00edvel a partir de 27\/11 &#8211; 00h<\/strong><br \/>\nEUA &#8211; 2020<br \/>\nDire\u00e7\u00e3o: Catherine Cyran<br \/>\nElenco: Katrina Law, Carlo Marks, Steve Bacic, Brenda Matthews<br \/>\nFuncion\u00e1ria das empresas Darlington, Jessica (Katrina Law) \u00e9 promovida por Charles (Steve Bacic) \u00e0s v\u00e9speras do Natal. Mas, antes da advogada ocupar seu novo posto, seu chefe lhe pede um \u00faltimo favor: entregar suas sobrinhas \u00f3rf\u00e3s ao seu irm\u00e3o Max (Carlo Marks). Tamb\u00e9m herdeiro da companhia, ele \u00e9 conhecido por n\u00e3o levar as coisas muito a s\u00e9rio. Milagre de Natal ou n\u00e3o, Jessica acaba conhecendo um outro lado do milion\u00e1rio.<\/p>\n<h3>Um Buqu\u00ea de Natal<\/h3>\n<p>Jingle Bell Bride<br \/>\n<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/11\/umbuquedenatal2-1.jpg?resize=600%2C360&#038;ssl=1\" alt=\"Foto de Um Buqu\u00ea de Natal, em Telecine\" width=\"600\" height=\"360\" class=\"alignnone size-full wp-image-9344\" \/><br \/>\nDrama, Drama Rom\u00e2ntico<br \/>\n<strong>Dispon\u00edvel a partir de 27\/11 &#8211; 00h<\/strong><br \/>\nEUA &#8211; 2020<br \/>\nDire\u00e7\u00e3o: Allan Harmon<br \/>\nElenco: Julie Gonzalo, Ronnie Rowe, Bj Harrison, Keenan Mentzos<br \/>\nJessica (Julie Gonzalo) planeja casamentos em Nova York. \u00c0s v\u00e9speras do Natal, ela precisa viajar em busca de uma flor para conseguir uma promo\u00e7\u00e3o. Desesperada em meio ao caos, Jess conhece Matt (Ronnie Rowe), que acaba balan\u00e7ando seu cora\u00e7\u00e3o e mexendo com suas prioridades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um Natal Cinco Estrelas, O Natal dos Darlingtons e Um Buqu\u00ea de Natal s\u00e3o tr\u00eas filmes com tema de Natal em estreia no Telecine neste s\u00e1bado, dia 27<\/p>\n","protected":false},"author":1,"featured_media":9342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[488],"tags":[63],"class_list":["post-9341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-telecine","tag-telecine","wpcat-488-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/11\/umnatalcincostars-1.jpg?fit=587%2C360&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-2qF","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/9341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=9341"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/9341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/9342"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=9341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=9341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=9341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}