{"id":9020,"date":"2021-11-06T10:54:34","date_gmt":"2021-11-06T13:54:34","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=9020"},"modified":"2021-11-15T11:01:51","modified_gmt":"2021-11-15T14:01:51","slug":"alerta-vermelho-e-marighella-entre-as-estreias-recentes-nos-cinemas","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/alerta-vermelho-e-marighella-entre-as-estreias-recentes-nos-cinemas\/","title":{"rendered":"&#8216;Alerta Vermelho&#8217; e &#8216;Spencer&#8217; entre as estreias recentes nos cinemas"},"content":{"rendered":"<p><em>Not\u00edcias de Filmes em Estreia nos Cinemas:<\/em><br \/>\n<img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/10\/aalertaverm.jpg?resize=600%2C360&#038;ssl=1\" alt=\"Foto de Alerta Vermelho, em filmes em estreia no cinema\" width=\"600\" height=\"360\" class=\"alignnone size-full wp-image-8945\" \/><\/p>\n<h3>Alerta Vermelho<\/h3>\n<p>A\u00e7\u00e3o<br \/>\n<strong>Estreia em 04 de novembro<\/strong><br \/>\nDire\u00e7\u00e3o: Rawson Marshall Thurber<br \/>\nCom Dwayne Johnson, Ryan Reynolds e Gal Gadot<br \/>\nUm agente do FBI (Dwayne Johnson) persegue o ladr\u00e3o de arte mais procurado do mundo. Ele s\u00f3 n\u00e3o esperava ter seu alvo (Ryan Reynolds) como parceiro para prender uma bandida muito esperta (Gal Gadot).<br \/>\n<iframe width=\"728\" height=\"410\" src=\"https:\/\/www.youtube.com\/embed\/SKJn8AWQo0o\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3>Marighella<\/h3>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/10\/marighella.jpg?resize=600%2C360&#038;ssl=1\" alt=\"Foto de Marighella, em estreias no Cinem\" width=\"600\" height=\"360\" class=\"alignnone size-full wp-image-8992\" \/><br \/>\nEstreia dia 04 de novembro<br \/>\nOrigem: Brasil<br \/>\nFilme de Wagner Moura<br \/>\nCom Seu Jorge, Adriana Esteves, Ana Paula Bouzas, Bella Camero, Herson Capri, Humberto Carr\u00e3o, Jorge Paz, Luiz Carlos Vasconcelos<br \/>\n1969. Marighella n\u00e3o teve tempo pra ter medo. De um lado, uma violenta ditadura militar. Do outro, uma esquerda intimidada. Cercado por guerrilheiros 30 anos mais novos e dispostos a reagir, o l\u00edder revolucion\u00e1rio escolheu a a\u00e7\u00e3o. Em \u201cMarighella\u201d, filme dirigido por Wagner Moura, o inimigo n\u00famero 1 do Brasil tenta articular uma frente de resist\u00eancia enquanto denuncia o horror da tortura e a inf\u00e2mia da censura instalados por um regime opressor. Em uma experi\u00eancia radical de combate, ele o faz em nome de um povo cujo apoio \u00e0 sua causa \u00e9 incerto \u2014 enquanto procura cumprir a promessa de reencontrar o filho, de quem por anos se manteve distante, como forma de proteg\u00ea-lo.<br \/>\n<iframe width=\"728\" height=\"410\" src=\"https:\/\/www.youtube.com\/embed\/fd8oX1u8gRA\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3>Querido Evan Hansen<\/h3>\n<p>(Dear Evan Hansen)<br \/>\nDrama, Musical<br \/>\nEstados Unidos<br \/>\nDire\u00e7\u00e3o: Stephen Chbosky<br \/>\nCom Amy Adams, Kaitlyn Dever, Julianne Moore, Ben Platt, Amandla Stenberg, Nik Dodani, Colton Ryan<br \/>\n<strong>Estreia em 11\/11\/2021<\/strong><br \/>\nAdapta\u00e7\u00e3o cinematogr\u00e1fica do musical vencedor dos pr\u00e9mios Tony e Grammy sobre Evan Hansen, um finalista de liceu com dist\u00farbios de Ansiedade Social e a sua viagem de auto-descoberta e aceita\u00e7\u00e3o ap\u00f3s o suic\u00eddio de um colega de turma.<br \/>\nO fen\u00f4meno da Broadway de tirar o f\u00f4lego torna-se um evento cinematogr\u00e1fico quando o vencedor do Tony, Grammy e Emmy, Ben Platt, repete seu papel como um estudante do ensino m\u00e9dio ansioso e isolado, ansiando por compreens\u00e3o e pertencimento em meio ao caos e crueldade da era da m\u00eddia social. Dirigido pelo aclamado cineasta Stephen Chbosky (As Vantagens de Ser Invis\u00edvel, Extraordin\u00e1rio), o filme foi escrito para as telonas pelo vencedor do Tony, Steven Levenson, com m\u00fasica e letras da equipe de compositores vencedora do Oscar\u00ae, Grammy e Tony Benj Pasek e Justin Paul (La La Land: Cantando Esta\u00e7\u00f5es, O Rei do Show). Apresentando can\u00e7\u00f5es ganhadoras do Grammy, incluindo o hino ic\u00f4nico &#8220;&#8221;You Will Be Found&#8221;&#8221;, &#8220;&#8221;Waving Through a Window&#8221;&#8221;, &#8220;&#8221;For Forever&#8221;&#8221; e &#8220;&#8221;Words Fail&#8221;&#8221;, Querido Evan Hansen estrela a seis vezes indicada ao Oscar\u00ae Amy Adams e a vencedora do Oscar\u00ae Julianne Moore, Kaitlyn Dever (Booksmart), Amandla Stenberg (O \u00d3dio que Voc\u00ea Semeia), Colton Ryan (Little Voice da Apple TV +), Nik Dodani (Atypical da Netflix), DeMarius Copes (Meninas Malvadas da Broadway) e Danny Pino (Law &#038; Order: Unidade de V\u00edtimas Especiais). Querido Evan Hansen \u00e9 produzido por Marc Platt (La La Land: Cantando Esta\u00e7\u00f5es, Caminhos da Floresta, O Retorno de Mary Poppins) e Adam Siegel (Dose Dupla, Drive), e tem como produtores executivos Michael Bederman, Steven Levenson, Benj Pasek e Justin Paul. A Universal Pictures distribui o filme em todos os territ\u00f3rios.<br \/>\n<iframe width=\"728\" height=\"410\" src=\"https:\/\/www.youtube.com\/embed\/o9xbS6PKmRA\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3>A Bab\u00e1 &#8211; O Chamado das Sombras<\/h3>\n<p>Terror<br \/>\n<strong>Estreia em 11 de novembro<\/strong><br \/>\nDire\u00e7\u00e3o: Svyatoslav Podgaevskiy, Nathalia Hencker<br \/>\nCom Oleg Chugunov, Glafira Golubeva, Artyom Zhigulin<br \/>\nUma jovem fam\u00edlia contrata uma bab\u00e1 para tomar conta de suas crian\u00e7as, mas depois de conseguir a confian\u00e7a dos pais, a nova guardi\u00e3 come\u00e7a a exibir um comportamento estranho. Quando seus pais se recusam a acreditar nele, o filho Egor precisa enfrentar a situa\u00e7\u00e3o sozinho\u2026 at\u00e9 que ele descobre que a bab\u00e1 e sua irm\u00e3zinha desapareceram sem deixar rastro. Com seus pais em um estado hipnotizado, sem lembran\u00e7as de sua pr\u00f3pria filha, Egor percebe que sua fam\u00edlia foi v\u00edtima de um antigo dem\u00f4nio chamado Baba Yaga. Com a ajuda dos seus amigos, ele deve parar a entidade antes que os seus pais esque\u00e7am dele tamb\u00e9m.<br \/>\n<iframe width=\"728\" height=\"410\" src=\"https:\/\/www.youtube.com\/embed\/wHuSAzYQQtc\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3>A Profissional<\/h3>\n<p>A\u00e7\u00e3o<br \/>\n<strong>Estreia em 11 de novembro<\/strong><br \/>\nDire\u00e7\u00e3o: Martin Campbell<br \/>\nCom Maggie Q, Samuel L. Jackson, Michael Keaton<br \/>\nAnna (Maggie Q) \u00e9 uma matadora de aluguel extremamente habilidosa treinada pelo lend\u00e1rio assassino Moody (Samuel L. Jackson), que a ensinou tudo que sabe e era a \u00fanica figura paterna que ela j\u00e1 teve. Quando Moody \u00e9 brutalmente assassinado por inimigos, Anna jura se vingar e acaba caindo em um jogo de gato e rato com um man\u00edaco homicida (Michael Keaton) cuja obsess\u00e3o por ela vai al\u00e9m de suas habilidades como matadora.<br \/>\n<iframe width=\"728\" height=\"410\" src=\"https:\/\/www.youtube.com\/embed\/Fk7syNe58I0\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3>Spencer<\/h3>\n<p>Biogr\u00e1fico<br \/>\n<strong>Estreia em 11 de novembro<\/strong><br \/>\nDire\u00e7\u00e3o: Pablo Larra\u00edn<br \/>\nCom Kristen Stewart, Amy Manson, Sally Hawkins<br \/>\nSpencer \u00e9 um filme sobre a princesa Diana depois que ela decidiu terminar seu relacionamento com o pr\u00edncipe Charles.<br \/>\nO filme se passa nos anos 90. Diana passa o feriado do Natal com a fam\u00edlia real em Norfolk, Reino Unido. Apesar das bebidas, brincadeiras e comidas em que sabe o script, esse final de ano vai ser diferente. Ap\u00f3s rumores de trai\u00e7\u00e3o, a princesa se v\u00ea em um impasse quando percebe que o seu casamento com o Pr\u00edncipe Charles n\u00e3o est\u00e1 dando certo. Mesmo com os dois filhos, ela decide o deixar. Spencer \u00e9 apenas uma especula\u00e7\u00e3o do que pode ter acontecido durante esses turbulentos dias e not\u00edcias.<br \/>\n<iframe width=\"728\" height=\"410\" src=\"https:\/\/www.youtube.com\/embed\/tZhqbnVc_EI\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3>\u00daltimas not\u00edcias:<\/p>\n<h3>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-6bd8abdjeq\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/temporada-3-de-euphoria-estreia-domingo-dia-12-4-na-hbo-max\/\" class=\"_blank\" target=\"_blank\" >Temporada 3 de Euphoria estreia domingo, dia 12\/4, na HBO Max<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-netflix-estreia-live-action-de-cavaleiros-do-zodiaco\/\" class=\"_blank\" target=\"_blank\" >A Netflix estreia live-action de Cavaleiros do Zod\u00edaco<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/minha-fera-estreia-no-globoplay-neste-sabado-28-de-marco\/\" class=\"_blank\" target=\"_blank\" >&#8220;Minha Fera&#8221; estreia no Globoplay neste s\u00e1bado, 28 de mar\u00e7o<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/supergirl-chega-aos-cinemas-em-junho\/\" class=\"_blank\" target=\"_blank\" >Supergirl chega aos cinemas em junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-os-casos-de-harry-hole-estreia-na-netflix-nesta-quinta-dia-26\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie &#8216;Os casos de Harry Hole&#8217; estreia na Netflix nesta quinta, dia 26<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/chamas-do-destino-cicek-abre-mao-de-fortuna-para-ficar-com-atlas\/\" class=\"_blank\" target=\"_blank\" >Chamas do Destino:  Cicek abre m\u00e3o de fortuna para ficar com Atlas<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/bridgerton-4at-parte-2-chega-nesta-quinta-26-na-netflix\/\" class=\"_blank\" target=\"_blank\" >Bridgerton (4\u00aaT), parte 2 chega nesta quinta (26), na Netflix<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/programacao-de-filmes-na-tv-para-o-fim-de-semana\/\" class=\"_blank\" target=\"_blank\" >Programa\u00e7\u00e3o de filmes na TV para o fim de semana<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-aniela-chega-na-netflix-dia-11-de-junho\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie Aniela chega na Netflix dia 11 de junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-idade-dourada-t3-estreia-no-max-dia-21-de-junho\/\" class=\"_blank\" target=\"_blank\" >A Idade Dourada (T3) estreia no Max em 21 de junho<\/a><\/h4><\/div><\/div><\/div><\/div><\/div><\/p>\n<h3>Saiba mais<\/h3>\n<p><a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/os-filmes-e-series-que-estreiam-na-netflix-em-novembro-21\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias de in\u00e9ditos na Netflix no m\u00eas de novembro\/2021<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/filmes-e-series-ineditos-em-estreia-na-semana-na-netflix\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias da semana na Netflix<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/o-que-ha-de-novo-no-globoplay\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias e novidades no Globoplay<\/strong><\/a><br \/>\n<a href=\"\/\/tvnovelas.com.br\/filmes\/filmes-em-estreia-nos-cinemas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias e novidades no Cinema<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.tvnovelas.com.br\/novelas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Resumos de novelas<\/strong><\/a><br \/>\n<a href=\"https:\/\/caetenews.com.br\/semana\/filmes-da-globo-na-sessao-da-tarde-desta-semana\/\" rel=\"noopener\" target=\"_blank\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Alerta Vermelho&#8217; e &#8216;Marighella&#8217; entre as estreias no cinema na quinta, dia 4 de novembro. Em Alerta Vermelho, Um agente do FBI (Dwayne Johnson)&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":8945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[203],"tags":[108],"class_list":["post-9020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cinema","tag-cinema","wpcat-203-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/10\/aalertaverm.jpg?fit=600%2C360&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-2lu","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/9020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=9020"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/9020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/8945"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=9020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=9020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=9020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}