{"id":8815,"date":"2021-10-21T15:39:30","date_gmt":"2021-10-21T18:39:30","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=8815"},"modified":"2021-10-21T15:39:30","modified_gmt":"2021-10-21T18:39:30","slug":"infantil-maya-e-os-tres-guerreiros-chega-a-netflix-nesta-sexta-22","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/infantil-maya-e-os-tres-guerreiros-chega-a-netflix-nesta-sexta-22\/","title":{"rendered":"Infantil &#8216;Maya e os Tr\u00eas Guerreiros&#8217; chega \u00e0 Netflix nesta sexta, 22"},"content":{"rendered":"<p><em>Not\u00edcias da Netflix:<\/em><br \/>\n<img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/10\/mayaeostres.jpg?resize=600%2C360&#038;ssl=1\" alt=\"Foto de Maya e os Tr\u00eas Guerreiros, em Netflix\" width=\"600\" height=\"360\" class=\"alignnone size-full wp-image-8816\" \/><\/p>\n<h3>Maya e os Tr\u00eas Guerreiros<\/h3>\n<p>S\u00e9ries &#8211; Crian\u00e7as, A\u00e7\u00e3o, Fantasia e fant\u00e1stico<br \/>\n<strong>Estreia em 22 de outubro<\/strong><br \/>\nNum mundo fant\u00e1stico e cheio de magia, uma princesa guerreira mesoamericana parte numa viagem \u00e9pica para cumprir uma antiga profecia e salvar a humanidade dos vingativos deuses do submundo.<br \/>\nSinopse<br \/>\nNum universo fant\u00e1stico em que a magia faz o mundo girar e quatro reinos imperam, uma princesa guerreira corajosa e rebelde chamada Maya est\u00e1 prestes a celebrar o d\u00e9cimo quinto anivers\u00e1rio e a sua coroa\u00e7\u00e3o. Mas tudo muda quando os deuses do submundo chegam e anunciam que a vida de Maya pertence ao deus da guerra, o pre\u00e7o a pagar pelo passado secreto da fam\u00edlia dela. Se a princesa recusar, o mundo inteiro vai sofrer a vingan\u00e7a dos deuses. Para salvar a fam\u00edlia, os amigos e a pr\u00f3pria vida, Maya parte numa emocionante aventura para cumprir a antiga profecia que prev\u00ea a vinda de tr\u00eas grandes guerreiros, que a ajudar\u00e3o a derrotar os deuses e salvar a humanidade.<br \/>\nDo criador Jorge R. Guti\u00e9rrez (&#8220;El Tigre&#8221;, &#8220;O Livro da Vida&#8221;), &#8220;Maya e Os Tr\u00eas&#8221; \u00e9 um evento animado Netflix em nove cap\u00edtulos \u00e9picos, uma aventura cheia de alma e humor num mundo de fantasia inspirado por um misto rico e din\u00e2mico das mitologias asteca, maia e inca, bem como a cultura caribenha dos dias de hoje. Zoe Salda\u00f1a \u00e9 a Princesa Maya, Gabriel Iglesias \u00e9 Picchu, Allen Maldonado \u00e9 Rico, Stephanie Beatriz \u00e9 Chimi, Diego Luna \u00e9 Zatz, Gael Garc\u00eda Bernal \u00e9 os Trig\u00e9meos Jaguares, Alfred Molina \u00e9 o deus da guerra, Kate del Castillo \u00e9 a deusa da morte, Danny Trejo \u00e9 o deus dos terramotos, Cheech Marin \u00e9 os deuses do vento e das tempestades, Rosie Perez \u00e9 a deusa dos jacar\u00e9s, Queen Latifah \u00e9 a Gran Bruja, Wyclef Jean \u00e9 o Gran Brujo, Jorge R. Guti\u00e9rrez \u00e9 o Rei Teca, Sandra Equihua \u00e9 a Rainha Teca, Isabela Merced \u00e9 a Rainha Vi\u00fava, Chelsea Rendon \u00e9 a deusa das tatuagens, Joaqu\u00edn Cos\u00edo \u00e9 o deus dos morcegos, Carlos Alazraqui \u00e9 o deus da magia negra, Eric Bauza \u00e9 o deus dos animais da selva, e Rita Moreno \u00e9 Ah Puch.<br \/>\n<iframe width=\"728\" height=\"410\" src=\"https:\/\/www.youtube.com\/embed\/eZiBajMjYUo\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3>\u00daltimas not\u00edcias:<\/p>\n<h3>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-6bd8abdjeq\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/temporada-3-de-euphoria-estreia-domingo-dia-12-4-na-hbo-max\/\" class=\"_blank\" target=\"_blank\" >Temporada 3 de Euphoria estreia domingo, dia 12\/4, na HBO Max<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-netflix-estreia-live-action-de-cavaleiros-do-zodiaco\/\" class=\"_blank\" target=\"_blank\" >A Netflix estreia live-action de Cavaleiros do Zod\u00edaco<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/minha-fera-estreia-no-globoplay-neste-sabado-28-de-marco\/\" class=\"_blank\" target=\"_blank\" >&#8220;Minha Fera&#8221; estreia no Globoplay neste s\u00e1bado, 28 de mar\u00e7o<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/supergirl-chega-aos-cinemas-em-junho\/\" class=\"_blank\" target=\"_blank\" >Supergirl chega aos cinemas em junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-os-casos-de-harry-hole-estreia-na-netflix-nesta-quinta-dia-26\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie &#8216;Os casos de Harry Hole&#8217; estreia na Netflix nesta quinta, dia 26<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/chamas-do-destino-cicek-abre-mao-de-fortuna-para-ficar-com-atlas\/\" class=\"_blank\" target=\"_blank\" >Chamas do Destino:  Cicek abre m\u00e3o de fortuna para ficar com Atlas<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/bridgerton-4at-parte-2-chega-nesta-quinta-26-na-netflix\/\" class=\"_blank\" target=\"_blank\" >Bridgerton (4\u00aaT), parte 2 chega nesta quinta (26), na Netflix<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/programacao-de-filmes-na-tv-para-o-fim-de-semana\/\" class=\"_blank\" target=\"_blank\" >Programa\u00e7\u00e3o de filmes na TV para o fim de semana<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-aniela-chega-na-netflix-dia-11-de-junho\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie Aniela chega na Netflix dia 11 de junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-idade-dourada-t3-estreia-no-max-dia-21-de-junho\/\" class=\"_blank\" target=\"_blank\" >A Idade Dourada (T3) estreia no Max em 21 de junho<\/a><\/h4><\/div><\/div><\/div><\/div><\/div><\/p>\n<h3>Saiba mais<\/h3>\n<p><a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/minisserie-criada-maid-abre-as-estreias-de-outubro-da-netflix\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias de in\u00e9ditos na Netflix no m\u00eas de outubro\/2021<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/filmes-e-series-ineditos-em-estreia-na-semana-na-netflix\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias da semana na Netflix<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/o-que-ha-de-novo-no-globoplay\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias e novidades no Globoplay<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.tvnovelas.com.br\/novelas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Resumos de novelas<\/strong><\/a><br \/>\n<a href=\"https:\/\/caetenews.com.br\/semana\/filmes-da-globo-na-sessao-da-tarde-desta-semana\/\" rel=\"noopener\" target=\"_blank\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Maya e os Tr\u00eas Guerreiros&#8217;. Num mundo fant\u00e1stico e cheio de magia, uma princesa guerreira mesoamericana parte numa viagem \u00e9pica para cumprir&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":8816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[92],"tags":[71,70],"class_list":["post-8815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-netflix","tag-estreias-na-netflix","tag-netflix","wpcat-92-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/10\/mayaeostres.jpg?fit=600%2C360&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-2ib","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/8815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=8815"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/8815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/8816"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=8815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=8815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=8815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}