{"id":8798,"date":"2021-10-20T13:01:38","date_gmt":"2021-10-20T16:01:38","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=8798"},"modified":"2021-10-20T13:01:38","modified_gmt":"2021-10-20T16:01:38","slug":"serie-desalma-sera-exibida-no-corujao-misterio-a-partir-de-segunda-dia-25","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/serie-desalma-sera-exibida-no-corujao-misterio-a-partir-de-segunda-dia-25\/","title":{"rendered":"S\u00e9rie &#8216;Desalma&#8217;  ser\u00e1 exibida no &#8216;Coruj\u00e3o Mist\u00e9rio&#8217; a partir de segunda, dia 25"},"content":{"rendered":"<p><em>Desalma em Coruj\u00e3o Mist\u00e9rio:<\/em><br \/>\n<img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-8800 size-full\" title=\"(Foto: Globo \/ Estevam Avellar)\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/10\/30255.jpg?resize=600%2C360&#038;ssl=1\" alt=\"Foto de Haia (Cassia Kis), em Desalma\" width=\"600\" height=\"360\" \/><br \/>\nNo clima do Halloween, &#8216;Coruj\u00e3o Mist\u00e9rio&#8217; ir\u00e1 apresentar o drama sobrenatural &#8216;Desalma&#8217;. Exibida originalmente no Globoplay, a s\u00e9rie ir\u00e1 ao ar pela primeira vez na TV Globo em cinco epis\u00f3dios duplos, a partir do pr\u00f3ximo dia 25. A obra criada e escrita por Ana Paula Maia com dire\u00e7\u00e3o art\u00edstica de Carlos Manga Jr., se passa na pequena Br\u00edgida, cidade fict\u00edcia do interior do Sul do pa\u00eds, onde fen\u00f4menos sobrenaturais assombram a popula\u00e7\u00e3o ao longo de d\u00e9cadas, enquanto rituais de bruxaria prometem trazer de volta ao mundo dos vivos almas de pessoas que j\u00e1 se foram. Os moradores pagam pelas escolhas feitas no passado e s\u00e3o atormentados por eventos sobrenaturais.<\/p>\n<p>Grande f\u00e3 de hist\u00f3rias do terror, a autora Ana Paula Maia \u00e9 vencedora do Pr\u00eamio S\u00e3o Paulo de Literatura e tem livros traduzidos em diversos pa\u00edses. Agora, estreia no audiovisual com esse drama&#8217;. &#8220;\u2018Desalma\u2019 \u00e9 um drama sobrenatural, com camadas. \u00c9 a n\u00e3o aceita\u00e7\u00e3o da morte e tem rela\u00e7\u00e3o com transmigra\u00e7\u00e3o de almas. Esse tema tem muito a ver com o meu universo. Gosto de terror e sobrenatural desde pequena e tenho uma trajet\u00f3ria com hist\u00f3rias do g\u00eanero em toda a minha vida. At\u00e9 ent\u00e3o, eu nunca tinha conseguido levar isso para a literatura. Vi no audiovisual essa oportunidade. Escrevi sozinha, de uma forma bem parecida como eu escrevo meus livros&#8221;, conta a autora, que escolheu retratar a cultura ucraniana ao contar uma hist\u00f3ria envolvendo mist\u00e9rios. \u201cFalamos da migra\u00e7\u00e3o do povo de um pa\u00eds que existe hoje no Brasil, mas pouca gente conhece. A maior comunidade ucraniana fora da Ucr\u00e2nia \u00e9 no Brasil. Eles mant\u00eam vivas as festas, as tradi\u00e7\u00f5es. O leste europeu \u00e9 extremamente m\u00edstico. Peguei essa atmosfera muito rica culturalmente para contar uma hist\u00f3ria com elementos sobrenaturais&#8221;, revela.<\/p>\n<p>Na hist\u00f3ria, que tem como pano de fundo a mitologia eslava, a floresta de \u00e1rvores altas e as enormes cachoeiras t\u00eam protagonismo. A trama se passa em duas d\u00e9cadas, com uma narrativa repleta de idas e vindas, em que nada \u00e9 entregue facilmente ao espectador. &#8220;Na dire\u00e7\u00e3o, criamos atmosferas que levam a imagina\u00e7\u00e3o a trabalhar. Voc\u00ea n\u00e3o v\u00ea as coisas, tem a sensa\u00e7\u00e3o. Gosto de chamar de dire\u00e7\u00e3o sugerida: uma porta fechada que quando aparece de volta est\u00e1 aberta, a c\u00e2mera que levemente vai se aproximando de um ambiente em que nada acontece\u201d, explica o diretor art\u00edstico Carlos Manga Jr.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone wp-image-8801 size-full\" title=\" ((Foto: Andr\u00e9 Hawk\/Globoplay)\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/10\/30256.jpg?resize=600%2C360&#038;ssl=1\" alt=\"Foto des bruxas, Haia e Halyna, em Desalma\" width=\"600\" height=\"360\" \/><br \/>\nO elenco de &#8216;Desalma&#8217; conta com nomes j\u00e1 conhecidos do grande p\u00fablico como Cassia Kis, Claudia Abreu e Maria Ribeiro e atores com caracter\u00edsticas f\u00edsicas do leste europeu escalados em S\u00e3o Paulo, Santa Catarina, Porto Alegre, Minas Gerais e Rio de Janeiro, entre eles, Anna Melo, Eduardo Borelli, Nath\u00e1lia Falc\u00e3o, Giovanni de Lorenzi e Nath\u00e1lia Garcia. &#8220;Os atores menos conhecidos do grande p\u00fablico representam 75% do nosso elenco. Eles est\u00e3o em papeis de destaque da hist\u00f3ria. Ao mesmo tempo, temos nomes fortes da dramaturgia como Cassia Kis, Claudia Abreu e Maria Ribeiro em personagens diferentes do que estamos acostumados a v\u00ea-las\u201d, explica Manga, ressaltando que essa mistura acentua a sensa\u00e7\u00e3o de estranheza no p\u00fablico.<\/p>\n<p>\u2018Desalma\u2019 \u00e9 uma s\u00e9rie criada e escrita por Ana Paula Maia com dire\u00e7\u00e3o art\u00edstica de Carlos Manga Jr. e dire\u00e7\u00e3o de Jo\u00e3o Paulo Jabur e Pablo M\u00fcller. Exibida originalmente no Globoplay, a primeira temporada de &#8216;Desalma&#8217; vai ao ar na TV Globo diariamente a partir do pr\u00f3ximo dia 25, em cinco epis\u00f3dios duplos, ap\u00f3s &#8216;Conversa com Bial&#8217;.<\/p>\n<h3>\u00daltimas not\u00edcias:<\/h3>\n<h3><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-6bd8abdjeq\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/temporada-3-de-euphoria-estreia-domingo-dia-12-4-na-hbo-max\/\" class=\"_blank\" target=\"_blank\" >Temporada 3 de Euphoria estreia domingo, dia 12\/4, na HBO Max<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-netflix-estreia-live-action-de-cavaleiros-do-zodiaco\/\" class=\"_blank\" target=\"_blank\" >A Netflix estreia live-action de Cavaleiros do Zod\u00edaco<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/minha-fera-estreia-no-globoplay-neste-sabado-28-de-marco\/\" class=\"_blank\" target=\"_blank\" >&#8220;Minha Fera&#8221; estreia no Globoplay neste s\u00e1bado, 28 de mar\u00e7o<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/supergirl-chega-aos-cinemas-em-junho\/\" class=\"_blank\" target=\"_blank\" >Supergirl chega aos cinemas em junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-os-casos-de-harry-hole-estreia-na-netflix-nesta-quinta-dia-26\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie &#8216;Os casos de Harry Hole&#8217; estreia na Netflix nesta quinta, dia 26<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/chamas-do-destino-cicek-abre-mao-de-fortuna-para-ficar-com-atlas\/\" class=\"_blank\" target=\"_blank\" >Chamas do Destino:  Cicek abre m\u00e3o de fortuna para ficar com Atlas<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/bridgerton-4at-parte-2-chega-nesta-quinta-26-na-netflix\/\" class=\"_blank\" target=\"_blank\" >Bridgerton (4\u00aaT), parte 2 chega nesta quinta (26), na Netflix<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/programacao-de-filmes-na-tv-para-o-fim-de-semana\/\" class=\"_blank\" target=\"_blank\" >Programa\u00e7\u00e3o de filmes na TV para o fim de semana<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-aniela-chega-na-netflix-dia-11-de-junho\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie Aniela chega na Netflix dia 11 de junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-idade-dourada-t3-estreia-no-max-dia-21-de-junho\/\" class=\"_blank\" target=\"_blank\" >A Idade Dourada (T3) estreia no Max em 21 de junho<\/a><\/h4><\/div><\/div><\/div><\/div><\/div><\/h3>\n<h3>Saiba mais<\/h3>\n<p><a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/minisserie-criada-maid-abre-as-estreias-de-outubro-da-netflix\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias de in\u00e9ditos na Netflix no m\u00eas de outubro\/2021<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/filmes-e-series-ineditos-em-estreia-na-semana-na-netflix\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias da semana na Netflix<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/o-que-ha-de-novo-no-globoplay\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias e novidades no Globoplay<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.tvnovelas.com.br\/novelas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Resumos de novelas<\/strong><\/a><br \/>\n<a href=\"https:\/\/caetenews.com.br\/semana\/filmes-da-globo-na-sessao-da-tarde-desta-semana\/\" target=\"_blank\" rel=\"noopener\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No clima do Halloween, &#8216;Coruj\u00e3o Mist\u00e9rio&#8217; ir\u00e1 apresentar o drama sobrenatural &#8216;Desalma&#8217;. Exibida originalmente no Globoplay, a s\u00e9rie ir\u00e1 ao&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[210],"tags":[61,667,412,58],"class_list":["post-8798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tv","tag-corujao","tag-desalma","tag-filmes-da-globo","tag-filmes-na-tv","wpcat-210-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/10\/30255.jpg?fit=600%2C360&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-2hU","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/8798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=8798"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/8798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/8800"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=8798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=8798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=8798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}