{"id":8623,"date":"2021-10-07T17:09:04","date_gmt":"2021-10-07T20:09:04","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=8623"},"modified":"2021-10-07T17:09:04","modified_gmt":"2021-10-07T20:09:04","slug":"minta-comigo-chega-com-os-dramas-conjugais-de-anna-e-jake-ao-globoplay-nesta-quinta-7","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/minta-comigo-chega-com-os-dramas-conjugais-de-anna-e-jake-ao-globoplay-nesta-quinta-7\/","title":{"rendered":"&#8216;Minta Comigo&#8217; chega com os dramas conjugais de Anna e Jake ao Globoplay nesta quinta, 7"},"content":{"rendered":"<p><strong>Not\u00edcias do Globoplay:<\/strong><br \/>\n<img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/10\/mintacomigo.jpg?resize=600%2C360&#038;ssl=1\" alt=\"foto de Minta Comigo, em estreia no Globoplay\" width=\"600\" height=\"360\" class=\"alignnone size-full wp-image-8624\" \/><br \/>\nUma boa op\u00e7\u00e3o para quem deseja maratonar s\u00e9ries em apenas um fim de semana \u00e9 \u2018Minta Comigo\u2019, miniss\u00e9rie, com  quatro epis\u00f3dios chega nesta quinta-feira (7)  ao cat\u00e1logo do Globoplay. Em busca de um novo come\u00e7o para o casamento, Anna (Charlie Brooks), Jake (Brett Tucker) e os dois filhos pequenos fazem as malas e v\u00e3o morar em Melbourne, na Austr\u00e1lia, cidade natal de Jake.<\/p>\n<p>Com Anna retomando sua carreira profissional, o casal precisa contratar uma bab\u00e1 para ajudar com as crian\u00e7as. Quando Becky (Phoebe Roberts) chega para assumir a fun\u00e7\u00e3o, a vida da fam\u00edlia come\u00e7a a ficar estremecida. Ao perceber uma mudan\u00e7a no comportamento de Jake, Anna procura ref\u00fagio e faz amizade com Becky. Mas tudo n\u00e3o passa de uma arma\u00e7\u00e3o para provar que Anna n\u00e3o \u00e9 uma boa m\u00e3e.<\/p>\n<p>Em quatro epis\u00f3dios, muitas tens\u00f5es e reviravoltas marcam a vida dos Fallmont na s\u00e9rie \u2018Minta Comigo\u2019. O Globoplay tamb\u00e9m possui em seu portf\u00f3lio outras op\u00e7\u00f5es de s\u00e9ries curtas e maratonaveis para o final de semana, como: \u2018Belgravia\u2019, \u2018Sra. Wilson\u2019, \u2018A Verdade Sobre o Caso Harry Quebert\u2019, \u2018Entre Segredos e Mentiras\u2019, \u2018Morte de Rouxin\u00f3is\u2019 e \u2018Small Axe\u2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma boa op\u00e7\u00e3o para quem deseja maratonar s\u00e9ries em apenas um fim de semana \u00e9 \u2018Minta Comigo\u2019, miniss\u00e9rie, no Globoplay&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[168],"tags":[286,175],"class_list":["post-8623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-globoplay","tag-estreias-no-globoplay","tag-globoplay","wpcat-168-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/10\/mintacomigo.jpg?fit=600%2C360&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-2f5","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/8623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=8623"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/8623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/8624"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=8623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=8623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=8623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}