{"id":7894,"date":"2021-08-21T12:22:22","date_gmt":"2021-08-21T15:22:22","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=7894"},"modified":"2021-08-21T12:45:18","modified_gmt":"2021-08-21T15:45:18","slug":"conheca-os-protagonistas-de-quando-chama-o-coracao-que-estreia-na-record-dia-25","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/conheca-os-protagonistas-de-quando-chama-o-coracao-que-estreia-na-record-dia-25\/","title":{"rendered":"Conhe\u00e7a os protagonistas de &#8216;Quando Chama o Cora\u00e7\u00e3o&#8217; que estreia na Record, dia 25"},"content":{"rendered":"<p><strong>Em &#8216;Quando Chama o Cora\u00e7\u00e3o&#8217;:<\/strong><br \/>\n<img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-7817\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/08\/29670.jpg?resize=600%2C337&#038;ssl=1\" alt=\"Foto de divulga\u00e7\u00e3o de Quando Chama o Cora\u00e7\u00e3o\" width=\"600\" height=\"337\" \/><\/p>\n<p>A s\u00e9rie &#8216;Quando Chama o Cora\u00e7\u00e3o&#8217; estreia na Record, dia 25 de agosto. &#8216;Quando Chama o Cora\u00e7\u00e3o&#8217; (When Calls the Heart) \u00e9 uma s\u00e9rie, inspirada no livro hom\u00f4nimo de Janette Oke. A trama se passa no in\u00edcio do XX e conta a cativante hist\u00f3ria de Elizabeth Thatcher, uma jovem, bonita, culta e educada professora acostumada com sua vida na alta sociedade, que recebe sua primeira tarefa em sala de aula em Coal Valley. <a href=\"https:\/\/tvnovelas.com.br\/filmes\/quando-chama-o-coracao-ja-tem-data-de-estreia-na-record-dia-25\/\" rel=\"noopener\" target=\"_blank\"><strong>Leia mais.<\/strong><\/a><\/p>\n<h3>Quem \u00e9 Quem (Principais Personagens)<\/h3>\n<p><strong>Elizabeth Thatcher (Erin Krakow)<\/strong><br \/>\n<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/08\/rede2-1.jpg?resize=400%2C225&#038;ssl=1\" alt=\"Foto de Elizabeth Thatcher (Erin Krakow), em Quando Chama O Cora\u00e7\u00e3o \" width=\"400\" height=\"225\" class=\"alignnone size-full wp-image-7895\" \/><br \/>\nHerdeira de uma fam\u00edlia milion\u00e1ria da cidade de Hamilton, \u00e9 uma mulher bonita, culta, extrovertida e muito acostumada com o luxo e tamb\u00e9m os agitos da alta sociedade. \u00c9 filha do empres\u00e1rio William (Garwin Sanford) e da dondoca Gracie (Lynda Boyd). Professora em in\u00edcio de carreira, Elizabeth tem uma personalidade muito forte e n\u00e3o gosta nada de ser controlada.<\/p>\n<p><strong>Jack Thornton (Daniel Lissing)<\/strong><br \/>\n<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/08\/rede2-2.jpg?resize=400%2C225&#038;ssl=1\" alt=\"Foto de Jack Thornton (Daniel Lissing) em Quando Chama o Cora\u00e7\u00e3o\" width=\"400\" height=\"225\" class=\"alignnone size-full wp-image-7896\" \/><br \/>\nHomem conhecido por sua integridade e car\u00e1ter. Membro da Pol\u00edcia Real, \u00e9 transferido para Coal Valley e n\u00e3o demora a conquistar a simpatia dos moradores. Fica irado ao desconfiar que sua transfer\u00eancia para o vilarejo se deu por causa de uma ordem do pai de Elizabeth, por quem se apaixona.<\/p>\n<p><strong>Abigail Stanton (Lori Loughlin)<\/strong><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/08\/rede2-3.jpg?resize=400%2C225&#038;ssl=1\" alt=\"foto de Abigail Stanton (Lori Loughlin) em Quando Chama o Cora\u00e7\u00e3o\" width=\"400\" height=\"225\" class=\"alignnone size-full wp-image-7897\" \/><br \/>\nMulher forte, determinada e grande lideran\u00e7a em Coal Valley. Ela perde o marido e tamb\u00e9m o filho em uma explos\u00e3o na mina de carv\u00e3o. \u00c9 a melhor amiga de Elizabeth e trabalha duro para sustentar a casa, sem perder o bom humor e o senso de solidariedade. Torna-se dona de um caf\u00e9 na cidade.<\/p>\n<p><strong>Henry Gowen (Martin Cummins)<\/strong><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/08\/rede2-4.jpg?resize=400%2C225&#038;ssl=1\" alt=\"Foto de Henry Gowen (Martin Cummins) em Quando Chama o Cora\u00e7\u00e3o\" width=\"400\" height=\"225\" class=\"alignnone size-full wp-image-7898\" \/><br \/>\nO todo-poderoso da cidade \u00e9 dono da mineradora de carv\u00e3o. Mas ap\u00f3s um acidente que levou 47 mineiros \u00e0 morte, \u00e9 acusado de neglig\u00eancia e vai para a pris\u00e3o por roubar verbas de Coal Valley. Com a ajuda de Abigail, tem uma segunda chance e come\u00e7a seu pr\u00f3prio neg\u00f3cio de \u00f3leo na cidade.<\/p>\n<blockquote><p><a href=\"https:\/\/tvnovelas.com.br\/filmes\/quando-chama-o-coracao-ja-tem-data-de-estreia-na-record-dia-25\/\"><strong>Leia a sinopse da S\u00e9rie<\/strong><\/a><\/p><\/blockquote>\n<div class=\"fb-comments\" data-width=\"100%\" data-order-by=\"reverse_time\" data-numposts=\"5\"><\/div>\n<h3>\u00daltimas not\u00edcias:<\/h3>\n<h3><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-6bd8abdjeq\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/temporada-3-de-euphoria-estreia-domingo-dia-12-4-na-hbo-max\/\" class=\"_blank\" target=\"_blank\" >Temporada 3 de Euphoria estreia domingo, dia 12\/4, na HBO Max<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-netflix-estreia-live-action-de-cavaleiros-do-zodiaco\/\" class=\"_blank\" target=\"_blank\" >A Netflix estreia live-action de Cavaleiros do Zod\u00edaco<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/minha-fera-estreia-no-globoplay-neste-sabado-28-de-marco\/\" class=\"_blank\" target=\"_blank\" >&#8220;Minha Fera&#8221; estreia no Globoplay neste s\u00e1bado, 28 de mar\u00e7o<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/supergirl-chega-aos-cinemas-em-junho\/\" class=\"_blank\" target=\"_blank\" >Supergirl chega aos cinemas em junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-os-casos-de-harry-hole-estreia-na-netflix-nesta-quinta-dia-26\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie &#8216;Os casos de Harry Hole&#8217; estreia na Netflix nesta quinta, dia 26<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/chamas-do-destino-cicek-abre-mao-de-fortuna-para-ficar-com-atlas\/\" class=\"_blank\" target=\"_blank\" >Chamas do Destino:  Cicek abre m\u00e3o de fortuna para ficar com Atlas<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/bridgerton-4at-parte-2-chega-nesta-quinta-26-na-netflix\/\" class=\"_blank\" target=\"_blank\" >Bridgerton (4\u00aaT), parte 2 chega nesta quinta (26), na Netflix<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/programacao-de-filmes-na-tv-para-o-fim-de-semana\/\" class=\"_blank\" target=\"_blank\" >Programa\u00e7\u00e3o de filmes na TV para o fim de semana<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-aniela-chega-na-netflix-dia-11-de-junho\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie Aniela chega na Netflix dia 11 de junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-idade-dourada-t3-estreia-no-max-dia-21-de-junho\/\" class=\"_blank\" target=\"_blank\" >A Idade Dourada (T3) estreia no Max em 21 de junho<\/a><\/h4><\/div><\/div><\/div><\/div><\/div><\/h3>\n<p><strong>Saiba mais<\/strong><br \/>\n<a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/the-chair-valerie-2-e-todas-as-estreias-da-netflix-para-agosto\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias de in\u00e9ditos na Netflix no m\u00eas de agosto\/2021<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/filmes-e-series-ineditos-em-estreia-na-semana-na-netflix\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias da semana na Netflix<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/o-que-ha-de-novo-no-globoplay\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias e novidades no Globoplay<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.tvnovelas.com.br\/novelas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Resumos de novelas<\/strong><\/a><br \/>\n<a href=\"https:\/\/caetenews.com.br\/semana\/filmes-da-globo-na-sessao-da-tarde-desta-semana\/\" rel=\"noopener\" target=\"_blank\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>conhe\u00e7a os principais personages de &#8216;Quando Chama o Cora\u00e7\u00e3o&#8217; (When Calls the Heart), s\u00e9rie que estreia na Record, dia 25<\/p>\n","protected":false},"author":1,"featured_media":7895,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[210],"tags":[646,615],"class_list":["post-7894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tv","tag-quando-chama-o-coracao","tag-record","wpcat-210-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/08\/rede2-1.jpg?fit=400%2C225&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-23k","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/7894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=7894"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/7894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/7895"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=7894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=7894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=7894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}