{"id":7840,"date":"2021-08-17T15:01:16","date_gmt":"2021-08-17T18:01:16","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=7840"},"modified":"2021-08-17T15:01:57","modified_gmt":"2021-08-17T18:01:57","slug":"ilha-de-ferrobruno-sai-do-coma-disposto-a-conquistar-leona","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/ilha-de-ferrobruno-sai-do-coma-disposto-a-conquistar-leona\/","title":{"rendered":"&#8216;Ilha de Ferro: &#8216;Bruno sai do coma disposto a conquistar Leona"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-7841 size-full\" title=\"(Foto: Globo\/Raquel Cunha)\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/08\/29685.jpg?resize=600%2C360&#038;ssl=1\" alt=\"Foto de Sophie Charlotte, como Leona, em Ilha de Ferro\" width=\"600\" height=\"360\" \/><br \/>\nNesta segunda semana de &#8216;Ilha de Ferro&#8217;, as emo\u00e7\u00f5es a bordo da PLT-137 continuam. Nos pr\u00f3ximos epis\u00f3dios, Bruno (Klebber Toledo) sai do coma, para desespero de Dante (Cau\u00e3 Reymond) e Leona (Sophie Charlotte), que temem que o piloto revele a algu\u00e9m sobre a briga que os irm\u00e3os tiveram antes de o helic\u00f3ptero cair no mar.<\/p>\n<p>Bruno volta \u00e0 realidade tomado pela m\u00e1goa em rela\u00e7\u00e3o a Dante e disposto a ficar com Leona, custe o que custar. O rapaz se envolve em um esquema de desvio de \u00f3leo e, com o dinheiro que recebe, tenta impressionar a cunhada, afirmando que ao lado dele ela poder\u00e1 ter a vida de luxo e extravag\u00e2ncia que sempre mereceu.<\/p>\n<p>Tamb\u00e9m nos pr\u00f3ximos epis\u00f3dios, Dante e Bruno s\u00e3o surpreendidos pela volta da m\u00e3e, Isabel (C\u00e1ssia Kis), que os abandonou ainda crian\u00e7as. Ela procura Leona e conta sua vers\u00e3o da hist\u00f3ria, vendo na nora uma chance de conseguir se reconectar com os filhos.<\/p>\n<p>&#8216;Ilha de Ferro&#8217; \u00e9 criada e escrita por Max Mallmann e Adriana Lunardi, com supervis\u00e3o de Mauro Wilson, e tem dire\u00e7\u00e3o art\u00edstica e geral de Afonso Poyart, e dire\u00e7\u00e3o de Roberta Richard e Guga Sander. A obra, exibida originalmente no Globoplay, vai ao ar na TV Globo \u00e0s segundas e quartas ap\u00f3s \u2018Imp\u00e9rio\u2019; \u00e0s ter\u00e7as depois de \u2018The Masked Singer Brasil\u2019; \u00e0s quintas na sequ\u00eancia de \u2018Sob Press\u00e3o\u2019; e \u00e0s sextas ap\u00f3s \u2018Globo Rep\u00f3rter\u2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta segunda semana de &#8216;Ilha de Ferro&#8217;, as emo\u00e7\u00f5es a bordo da PLT-137 continuam. Nos pr\u00f3ximos epis\u00f3dios, Bruno (Klebber Toledo) sai do coma&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[210],"tags":[637,330],"class_list":["post-7840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tv","tag-ilha-de-ferro","tag-tv-globo","wpcat-210-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/08\/29685.jpg?fit=600%2C360&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-22s","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/7840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=7840"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/7840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/7841"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=7840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=7840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=7840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}