{"id":6852,"date":"2021-05-31T17:15:19","date_gmt":"2021-05-31T20:15:19","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=6852"},"modified":"2021-05-31T17:15:56","modified_gmt":"2021-05-31T20:15:56","slug":"temporada-5-de-sessao-de-terapia-estreia-no-globoplay-sexta-dia-4","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/temporada-5-de-sessao-de-terapia-estreia-no-globoplay-sexta-dia-4\/","title":{"rendered":"Temporada 5 de &#8216;Sess\u00e3o de Terapia&#8217;  estreia no Globoplay sexta, dia 4"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-6853 size-full\" title=\"(Foto: Globo\/Sess\u00e3o de Terapia)\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/05\/sessaodeterapia3.jpg?resize=600%2C355&#038;ssl=1\" alt=\"Foto de Selton Mello, como Caio\" width=\"600\" height=\"355\" \/><\/p>\n<p>Permeada por um tema que une todos os pacientes: a vida, a quinta temporada do original Globoplay \u2018Sess\u00e3o de Terapia\u2019 trar\u00e1 novos desafios para Caio Barone (Selton Mello). Sem Sofia por perto, ele precisa procurar um novo profissional para acompanh\u00e1-lo. \u00c9 ent\u00e3o que chega \u00e0 s\u00e9rie Davi Greco (Rodrigo Santoro), um terapeuta que cuida de adultos mas sobretudo de crian\u00e7as, fato que vai gerar uma tens\u00e3o entre eles. A nova temporada vai marcar o reencontro dos amigos Rodrigo e Selton, que n\u00e3o trabalham juntos desde a novela \u201cOlho no Olho\u201d de 1993, onde se conheceram. A quinta temporada da s\u00e9rie foi gravada nos Est\u00fadios Globo e os dez primeiros epis\u00f3dios estreiam no Globoplay no dia 04 de junho. A cada semana, cinco novos epis\u00f3dios sobem \u00e0 plataforma, sempre \u00e0s sextas-feiras.<\/p>\n<p>Dirigida por Selton Mello, escrita por Jaqueline Vargas e produzida por Roberto d&#8217;Avila, Sess\u00e3o de Terapia \u00e9 uma s\u00e9rie original Globoplay, produzida pelo GNT e Moonshot Pictures. \u201c\u00c9 muito comovente fazer essa s\u00e9rie, que na quinta temporada se passa durante a pandemia. O acolhimento e a escuta, que s\u00e3o fundamentos da terapia, s\u00e3o ainda mais necess\u00e1rios e o eixo da rela\u00e7\u00e3o do Caio com os pacientes se torna ainda mais s\u00f3lido e fundamental nesse momento. Atrav\u00e9s de uma fic\u00e7\u00e3o, voc\u00ea consegue tocar o cora\u00e7\u00e3o do p\u00fablico e fazer com que ele se enxergue e que ele sublime muitas dores, ent\u00e3o ela chega em um momento primordial\u201d, define Selton. Em \u2018Sess\u00e3o de Terapia\u2019, al\u00e9m de atuar, Selton dirige Rodrigo pela primeira vez.<\/p>\n<p>Os novos pacientes, que Caio atender\u00e1 durante a semana s\u00e3o: Manu (Let\u00edcia Colin), Tony (Christian Malheiros), Giovana (Luana Xavier) e Lidia (Miwa Yanagizawa). A nova temporada tamb\u00e9m abordar\u00e1 a vida familiar de Caio Barone. Com a not\u00edcia da morte da m\u00e3e, seu grande fantasma do passado, Caio entrar\u00e1 em conflito com sua irm\u00e3, Mariana (Bruna Chiaradia), que insiste para que ele conhe\u00e7a o irm\u00e3o, Miguel. Nosso protagonista resistir\u00e1, imaginando que este inesperado novo irm\u00e3o seja um cara mimado e irrespons\u00e1vel. Miguel ser\u00e1 vivido por Danton Mello, na grande participa\u00e7\u00e3o especial desta temporada. O encontro dos dois irm\u00e3os atores em cena ser\u00e1 in\u00e9dito, j\u00e1 que fizeram algumas pe\u00e7as de teatro juntos, pequenas participa\u00e7\u00f5es no cinema, mas nunca se encontraram em algo desse porte, na tv ou streaming.<\/p>\n<p>As duas primeiras temporadas de Sess\u00e3o de Terapia foram adaptadas do original israelense Be Tipul e a partir da terceira temporada, ainda no GNT, Jaqueline Vargas, Roberto d&#8217;Avila e Selton Mello desenvolveram temporadas in\u00e9ditas. A quarta temporada inaugurou uma nova fase, com o in\u00edcio da parceria com o Globoplay, sendo uma das s\u00e9ries originais mais vistas pelo p\u00fablico e que rendeu a nomea\u00e7\u00e3o \u00e0 Melhor S\u00e9rie de Fic\u00e7\u00e3o Tv Fechada\/Ott de 2020 pela Academia Brasileira de Cinema.<\/p>\n<p>&#8216;Sess\u00e3o de Terapia&#8217; estreia no Globoplay na sexta-feira, dia 4 de junho<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Permeada por um tema que une todos os pacientes: a vida, a quinta temporada do original Globoplay \u2018Sess\u00e3o de Terapia\u2019&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6853,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[168],"tags":[286,175,611],"class_list":["post-6852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-globoplay","tag-estreias-no-globoplay","tag-globoplay","tag-selton-mello","wpcat-168-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/05\/sessaodeterapia3.jpg?fit=600%2C355&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-1Mw","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/6852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=6852"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/6852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/6853"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=6852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=6852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=6852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}