{"id":6248,"date":"2021-04-12T01:18:46","date_gmt":"2021-04-12T04:18:46","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=6248"},"modified":"2021-04-11T11:55:03","modified_gmt":"2021-04-11T14:55:03","slug":"os-parcas-2-e-o-filme-do-tela-quente-nesta-segunda-12","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/os-parcas-2-e-o-filme-do-tela-quente-nesta-segunda-12\/","title":{"rendered":"&#8216;Os Par\u00e7as 2&#8217;  \u00b4\u00e9 o filme do  &#8216;Tela Quente&#8217; nesta segunda (12)"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-6251\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/04\/osparcas2.jpg?resize=600%2C338&#038;ssl=1\" alt=\"Foto de divulga\u00e7\u00e3o\" width=\"600\" height=\"338\" \/><br \/>\n&#8216;Os Par\u00e7as 2&#8217;, lan\u00e7ado em 2019, \u00e9 o filme em exibi\u00e7\u00e3o em Tela Quente, nesta segunda-feira (12), na Globo. Na com\u00e9dia de Cris D&#8217;Amato, sequ\u00eancia de &#8216;Os Par\u00e7as&#8217;, de 2017, ap\u00f3s saber que China deixou a cadeia e est\u00e1 em busca de vingan\u00e7a, Romeu (Bruno de Luca) precisa conseguir dinheiro para deixar o pa\u00eds o quanto antes. Para tanto, Toin (Tom Cavalcante), Ray Van (Whindersson Nunes) e Pil\u00f4ra (Tirulipa) juntam for\u00e7as para reformar uma col\u00f4nia de f\u00e9rias, de forma a atrair jovens de todo tipo. Quando o empreendimento enfim come\u00e7a a funcionar, eles logo passam a competir com uma col\u00f4nia vizinha, bem mais requintada. Mariana Santos, L\u00e9o Cidade, Cristina Mutarelli e Heslaine Vieira tamb\u00e9m comp\u00f5em o elenco, entre outros nomes. O filme traz participa\u00e7\u00e3o especial de Fabiana Karla, Paloma Bernardi, do jogador Falc\u00e3o e da cantora Simone.<\/p>\n<blockquote><p><a href=\"https:\/\/tvnovelas.com.br\/filmes\/programacao-diaria-dos-filmes-na-tv-aberta\/\">Confira a programa\u00e7\u00e3o da semana de filmes da TV aberta<\/a><\/p><\/blockquote>\n<div class=\"fb-comments\" data-width=\"100%\" data-order-by=\"reverse_time\" data-numposts=\"5\"><\/div>\n<p><strong>Saiba mais<\/strong><\/p>\n<h2 style=\"background-color: #ffa500; font-family: arial; padding-left: 10px;\"><a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\">Programa\u00e7\u00e3o de filmes na TV aberta<\/a><\/h2>\n<h2 style=\"background-color: #ffa500; font-family: arial; padding-left: 10px;\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/filmes-e-series-que-estreiam-no-globoplay-no-mes-de-abril\/\" target=\"_blank\" rel=\"noopener noreferrer\">Filmes e s\u00e9ries que estreiam no Globoplay no m\u00eas de abril<\/a><\/h2>\n<h2 style=\"background-color: #ffa500; font-family: arial; padding-left: 10px;\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/estreias-agendadas-na-netflix-para-o-mes-de-abril\/\" target=\"_blank\" rel=\"noopener noreferrer\">Estreias de in\u00e9ditos na Netflix no m\u00eas de abril\/2021<\/a><\/h2>\n<h2 style=\"background-color: #ffa500; font-family: arial; padding-left: 10px;\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/filmes-e-series-ineditos-em-estreia-na-semana-na-netflix\/\" target=\"_blank\" rel=\"noopener noreferrer\">Estreias na Netflix<\/a><\/h2>\n<p><a href=\"https:\/\/tvnovelas.com.br\/filmes\/netflix-revela-lista-de-filmes-para-2021-com-novidade-toda-semana-veja-lista-e-trailer\/\">Netflix revela lista de filmes para 2021, com novidade toda semana; veja lista e trailer<\/a><\/p>\n<h2 style=\"background-color: #ffa500; font-family: arial; padding-left: 10px;\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/filmes-series-e-novelas-em-estreia-no-globoplay\/\" target=\"_blank\" rel=\"noopener noreferrer\">Estreias no Globoplay em mar\u00e7o\/021<\/a><\/h2>\n<h2 style=\"background-color: #ffa500; font-family: arial; padding-left: 10px;\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/filmes-em-estreia-nos-cinemas\/\" target=\"_blank\" rel=\"noopener noreferrer\">Filmes em estreia nos cinemas<\/a><\/h2>\n<h2 style=\"background-color: #ffa500; font-family: arial; padding-left: 10px;\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvshow\/programacao-de-jogos-de-futebol-ao-vivo-na-tv\/\" target=\"_blank\" rel=\"noopener noreferrer\">Futebol ao vivo na TV<\/a><\/h2>\n<h2 style=\"background-color: #ffa500; font-family: arial; padding-left: 10px;\"><a href=\"https:\/\/www.tvnovelas.com.br\/novelas\/\" target=\"_blank\" rel=\"noopener noreferrer\">Resumos de todas as novelas<\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Os Par\u00e7as 2&#8217;, lan\u00e7ado em 2019, \u00e9 o filme em exibi\u00e7\u00e3o em Tela Quente, nesta segunda-feira (12), na Globo. Na&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6251,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[210],"tags":[412,58,64],"class_list":["post-6248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tv","tag-filmes-da-globo","tag-filmes-na-tv","tag-tela-quente","wpcat-210-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2021\/04\/osparcas2.jpg?fit=600%2C338&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-1CM","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/6248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=6248"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/6248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/6251"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=6248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=6248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=6248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}