{"id":5158,"date":"2020-12-15T17:46:15","date_gmt":"2020-12-15T20:46:15","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=5158"},"modified":"2020-12-15T17:46:15","modified_gmt":"2020-12-15T20:46:15","slug":"serie-o-clube-das-divorciadas-em-estreia-no-globoplay-nesta-terca-15","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/serie-o-clube-das-divorciadas-em-estreia-no-globoplay-nesta-terca-15\/","title":{"rendered":"S\u00e9rie \u2018O Clube das Divorciadas\u2019 em estreia no Globoplay nesta ter\u00e7a, 15"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2020\/12\/09_clubedivorciadas.jpg?resize=500%2C388&#038;ssl=1\" alt=\"Foto do cartaz de divulga\u00e7\u00e3o\" width=\"500\" height=\"388\" class=\"alignnone size-full wp-image-5159\" \/><\/p>\n<h3>O Clube das Divorciadas<\/h3\n<strong>Estreia em 15 de dezembro<\/strong><br \/>\nTr\u00eas amigas de longa data v\u00e3o se reencontrar ap\u00f3s algum tempo e redescobrir como a amizade delas \u00e9 fundamental para se apoiarem nos altos e baixos da vida. Essa \u00e9 a premissa da s\u00e9rie de com\u00e9dia \u2018O Clube das Divorciadas\u2019, que estreia nesta ter\u00e7a-feira, dia 15, no Globoplay. A obra \u00e9 baseada no filme \u2018O Clube das Desquitadas\u2019, que fez sucesso na d\u00e9cada de 90.<br \/>\nDepois de um per\u00edodo afastadas, as melhores amigas Ari (Ryan Michelle Bathe), Hazel (Jill Scott) e Bree (Michelle Buteau) se reencontram para se ajudarem nas dificuldades que est\u00e3o passando. Tudo come\u00e7a quando a estrela musical Hazel descobre que est\u00e1 sendo tra\u00edda pelo marido e um v\u00eddeo seu protagonizando um esc\u00e2ndalo viraliza pelas redes.<br \/>\nA partir deste momento, o trio de amigas se reaproxima, cada uma com seu problema particular. Ari abriu m\u00e3o da profiss\u00e3o para organizar a carreira pol\u00edtica do marido e vive um casamento insatisfat\u00f3rio, enquanto Bree passa por uma rotina exaustiva como uma m\u00e9dica workaholic e m\u00e3e de dois filhos. Ao longo do caminho, elas percebem que, enquanto tiverem umas \u00e0s outras, n\u00e3o h\u00e1 nada que n\u00e3o possam fazer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Clube das Divorciadas<\/p>\n","protected":false},"author":1,"featured_media":5159,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[168],"tags":[175,172],"class_list":["post-5158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-globoplay","tag-globoplay","tag-o-clube-das-divorciadas","wpcat-168-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2020\/12\/09_clubedivorciadas.jpg?fit=500%2C388&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-1lc","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/5158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=5158"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/5158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/5159"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=5158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=5158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=5158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}