{"id":14942,"date":"2023-11-09T14:12:41","date_gmt":"2023-11-09T17:12:41","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=14942"},"modified":"2023-11-09T14:12:41","modified_gmt":"2023-11-09T17:12:41","slug":"outlander-ceu-e-terra-nesta-sexta-dia-10-11","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/outlander-ceu-e-terra-nesta-sexta-dia-10-11\/","title":{"rendered":"&#8216;Outlander: C\u00e9u e Terra&#8217; nesta sexta, dia 10\/11"},"content":{"rendered":"<p><em>&#8216;Outlander: C\u00e9u e Terra&#8217;<\/em><br \/>\n<img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2023\/11\/1000.jpg?resize=728%2C410&#038;ssl=1\" alt=\"Foto em &#039;Outlander: C\u00e9u e Terra&#039;\" width=\"728\" height=\"410\" class=\"alignnone size-full wp-image-14943\" \/><br \/>\nEm &#8216;Outlander: C\u00e9u e Terra&#8217; nesta sexta, dia 10, No epis\u00f3dio 10, de Outlander, nesta sexta, dia 10, Claire corre para descobrir a origem de uma epidemia a bordo de um navio antes que centenas de marinheiros morram; quando Jamie se desentende com o Capit\u00e3o Raines, Fergus fica dividido entre a lealdade e o amor.<br \/>\nOutlander, temporada 03, \u00e9 exibida pela Band. O epis\u00f3dio 10 vai ao ar nesta sexta, dia 10, \u00e0s 22h30<br \/>\nDiretor: Philip John. Com Caitriona Balfe, Sam Heughan, Iona Claire , Romann Berrux, Scott Kyle , Duncan Lacroix, Andrew Gower<br \/>\n<!--FIM DO POST--><\/p>\n<h2>\u00daltimas publica\u00e7\u00f5es neste canal<\/h2>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-88c77f2wft\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/stuart-nao-consegue-salvar-o-universo-estreia-na-hbo-max-dia-23-7\/\" class=\"_self\" target=\"_self\" >Stuart N\u00e3o Consegue Salvar O Universo estreia na HBO Max dia 23\/7<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/estreias-na-hbo-max-no-mes-de-julho-26\/\" class=\"_self\" target=\"_self\" >Estreias na HBO Max no m\u00eas de julho\/26<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/estreias-no-disney-em-julho-26\/\" class=\"_self\" target=\"_self\" >Estreias no Disney+ em julho\/26<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/as-estreias-na-netflix-no-mes-de-julho-26\/\" class=\"_self\" target=\"_self\" >As estreias na Netflix no m\u00eas de julho\/26<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/estreias-na-netflix-nesta-quarta-1o-7\/\" class=\"_self\" target=\"_self\" >Estreias na Netflix nesta quarta (1\u00ba\/7)<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/temporada-3-de-euphoria-estreia-domingo-dia-12-4-na-hbo-max\/\" class=\"_self\" target=\"_self\" >Temporada 3 de Euphoria estreia domingo, dia 12\/4, na HBO Max<\/a><\/h4><\/div><\/div><\/div><\/div><\/div>\n<h2>\u00daltimas not\u00edcias das novelas<\/h2>\n<div class=\"wpra-display align\" data-display-id=\"1\" hx-target=\"this\" hx-swap=\"outerHTML\">    <div class=\"wp-rss-aggregator wpra-list-template \">\n        <ul class=\"rss-aggregator wpra-item-list wpra-item-list--bullets wpra-item-list--default\" start=\"1\">\n                <li class=\"wpra-item feed-item \">\n        <a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/a-historia-de-joana-caiman-tenta-matar-gabriel\/\" class=\"\" target=\"_blank\" rel=\"\" style=\"\">A Hist\u00f3ria de Joana: Caim\u00e1n tenta matar Gabriel<\/a>\n\n        <div class=\"wprss-feed-meta\">\n                <span class=\"feed-source\">\n        Source: tvnews\n    <\/span>\n                <span class=\"feed-date\">\n        Published on 2026-07-13\n    <\/span>\n            \n        <\/div>\n\n        \n    <\/li>    <li class=\"wpra-item feed-item \">\n        <a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/em-coracao-de-mae-aica-usa-rakan-como-acompanhante\/\" class=\"\" target=\"_blank\" rel=\"\" style=\"\">Em Cora\u00e7\u00e3o de M\u00e3e: Ai\u00e7a usa Rakan como acompanhante<\/a>\n\n        <div class=\"wprss-feed-meta\">\n                <span class=\"feed-source\">\n        Source: tvnews\n    <\/span>\n                <span class=\"feed-date\">\n        Published on 2026-07-13\n    <\/span>\n            \n        <\/div>\n\n        \n    <\/li>    <li class=\"wpra-item feed-item \">\n        <a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/em-coracao-de-mae-karsu-bebe-muito-fala-demais-e-bora-se-diverte\/\" class=\"\" target=\"_blank\" rel=\"\" style=\"\">Em Cora\u00e7\u00e3o de M\u00e3e: Karsu bebe muito, fala demais e Bora se diverte<\/a>\n\n        <div class=\"wprss-feed-meta\">\n                <span class=\"feed-source\">\n        Source: tvnews\n    <\/span>\n                <span class=\"feed-date\">\n        Published on 2026-07-12\n    <\/span>\n            \n        <\/div>\n\n        \n    <\/li>    <li class=\"wpra-item feed-item \">\n        <a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/quem-ama-cuida-adriana-acusa-ademir-de-ter-comprado-testemunha\/\" class=\"\" target=\"_blank\" rel=\"\" style=\"\">Quem Ama Cuida Adriana acusa Ademir de ter comprado testemunha<\/a>\n\n        <div class=\"wprss-feed-meta\">\n                <span class=\"feed-source\">\n        Source: tvnews\n    <\/span>\n                <span class=\"feed-date\">\n        Published on 2026-07-12\n    <\/span>\n            \n        <\/div>\n\n        \n    <\/li>    <li class=\"wpra-item feed-item \">\n        <a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-guerra-das-rosas-na-semana-13-a-17-7\/\" class=\"\" target=\"_blank\" rel=\"\" style=\"\">O que rola em Guerra das Rosas na semana 13 a 17\/7<\/a>\n\n        <div class=\"wprss-feed-meta\">\n                <span class=\"feed-source\">\n        Source: tvnews\n    <\/span>\n                <span class=\"feed-date\">\n        Published on 2026-07-11\n    <\/span>\n            \n        <\/div>\n\n        \n    <\/li>    <li class=\"wpra-item feed-item \">\n        <a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/acontece-em-coracao-de-mae-nos-proximos-capitulos-13-a-17-7\/\" class=\"\" target=\"_blank\" rel=\"\" style=\"\">Acontece em Cora\u00e7\u00e3o de M\u00e3e nos pr\u00f3ximos cap\u00edtulos (13 a 17\/7)<\/a>\n\n        <div class=\"wprss-feed-meta\">\n                <span class=\"feed-source\">\n        Source: tvnews\n    <\/span>\n                <span class=\"feed-date\">\n        Published on 2026-07-10\n    <\/span>\n            \n        <\/div>\n\n        \n    <\/li>    <li class=\"wpra-item feed-item \">\n        <a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/a-historia-de-joana-josefina-e-ramon-se-beijam\/\" class=\"\" target=\"_blank\" rel=\"\" style=\"\">A Hist\u00f3ria de Joana: Josefina e Ram\u00f3n se beijam<\/a>\n\n        <div class=\"wprss-feed-meta\">\n                <span class=\"feed-source\">\n        Source: tvnews\n    <\/span>\n                <span class=\"feed-date\">\n        Published on 2026-07-10\n    <\/span>\n            \n        <\/div>\n\n        \n    <\/li>    <li class=\"wpra-item feed-item \">\n        <a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/em-coracao-de-mae-reha-se-despede-de-karsu\/\" class=\"\" target=\"_blank\" rel=\"\" style=\"\">Em Cora\u00e7\u00e3o de M\u00e3e: Reha se despede de Karsu<\/a>\n\n        <div class=\"wprss-feed-meta\">\n                <span class=\"feed-source\">\n        Source: tvnews\n    <\/span>\n                <span class=\"feed-date\">\n        Published on 2026-07-10\n    <\/span>\n            \n        <\/div>\n\n        \n    <\/li>    <li class=\"wpra-item feed-item \">\n        <a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/guerra-das-rosas-sevket-agride-e-leva-yonca-desmaiada-para-a-mata\/\" class=\"\" target=\"_blank\" rel=\"\" style=\"\">Guerra das Rosas: Sevket agride e leva Yonca desmaiada para a mata<\/a>\n\n        <div class=\"wprss-feed-meta\">\n                <span class=\"feed-source\">\n        Source: tvnews\n    <\/span>\n                <span class=\"feed-date\">\n        Published on 2026-07-09\n    <\/span>\n            \n        <\/div>\n\n        \n    <\/li>    <li class=\"wpra-item feed-item \">\n        <a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/cansu-dere-protagoniza-iludida-na-record-com-estreia-em-agosto\/\" class=\"\" target=\"_blank\" rel=\"\" style=\"\">Cansu Dere protagoniza Iludida na Record com estreia em agosto<\/a>\n\n        <div class=\"wprss-feed-meta\">\n                <span class=\"feed-source\">\n        Source: tvnews\n    <\/span>\n                <span class=\"feed-date\">\n        Published on 2026-07-09\n    <\/span>\n            \n        <\/div>\n\n        \n    <\/li>\n        <\/ul>\n    <\/div> <\/div>\n<h3>Confira tamb\u00e9m<\/h3>\n<p><a href=\"https:\/\/www.tvnovelas.com.br\/novelas\/\"><strong>Confira os resumos da semana de todas novelas<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><br \/>\n<a href=\"https:\/\/caetenews.com.br\/semana\/filmes-da-globo-na-sessao-da-tarde-desta-semana\/\" target=\"_blank\" rel=\"noopener\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em &#8216;Outlander: C\u00e9u e Terra&#8217; nesta sexta, dia 10, No epis\u00f3dio 10, de Outlander, nesta sexta, dia 10, Claire corre para descobrir&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[210],"tags":[687,703],"class_list":["post-14942","post","type-post","status-publish","format-standard","hentry","category-tv","tag-band","tag-outlander","wpcat-210-id"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-3T0","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/14942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=14942"}],"version-history":[{"count":1,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/14942\/revisions"}],"predecessor-version":[{"id":14944,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/14942\/revisions\/14944"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=14942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=14942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=14942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}