{"id":11688,"date":"2022-09-11T20:23:45","date_gmt":"2022-09-11T23:23:45","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=11688"},"modified":"2022-09-11T17:29:55","modified_gmt":"2022-09-11T20:29:55","slug":"infantil-ada-batista-cientista-t-3-estreia-na-netflix-nesta-segunda-12-9","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/infantil-ada-batista-cientista-t-3-estreia-na-netflix-nesta-segunda-12-9\/","title":{"rendered":"Infantil &#8216;Ada Batista, cientista&#8217; (T 3) estreia na Netflix nesta segunda, 12\/9"},"content":{"rendered":"<p><em>Not\u00edcia de Estreia na Netflix:<\/em><\/p>\n<h2>Ada Batista, cientista<\/h2>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2022\/09\/adabatista.jpg?resize=600%2C360&#038;ssl=1\" alt=\"Foto de Ada Batista, cientista, em estreia na Netflix\" width=\"600\" height=\"360\" class=\"alignnone size-full wp-image-11689\" \/><br \/>\nS\u00e9rie &#8211; M\u00fasica para crian\u00e7as<br \/>\nTemporada 3<br \/>\nEstrelando: Amanda Christine, Nicholas Crovetti, Candace Kozak<br \/>\n<strong>Estreia em 12 de setembro<\/strong><br \/>\nNo laborat\u00f3rio de Ada Batista, ci\u00eancia \u00e9 pura divers\u00e3o. Ela e seus amiguinhos v\u00e3o viver aventuras incr\u00edveis!<br \/>\nEsta divertida s\u00e9rie mostra a import\u00e2ncia dos por qu\u00eas. Com produ\u00e7\u00e3o executiva de Chris Nee, e Barack e Michelle Obama.<br \/>\n<iframe width=\"728\" height=\"410\" src=\"https:\/\/www.youtube.com\/embed\/5pdKVlvoEU8\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2>\u00daltimas not\u00edcias:<\/h2>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-6bd8abdjeq\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/temporada-3-de-euphoria-estreia-domingo-dia-12-4-na-hbo-max\/\" class=\"_blank\" target=\"_blank\" >Temporada 3 de Euphoria estreia domingo, dia 12\/4, na HBO Max<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-netflix-estreia-live-action-de-cavaleiros-do-zodiaco\/\" class=\"_blank\" target=\"_blank\" >A Netflix estreia live-action de Cavaleiros do Zod\u00edaco<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/minha-fera-estreia-no-globoplay-neste-sabado-28-de-marco\/\" class=\"_blank\" target=\"_blank\" >&#8220;Minha Fera&#8221; estreia no Globoplay neste s\u00e1bado, 28 de mar\u00e7o<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/supergirl-chega-aos-cinemas-em-junho\/\" class=\"_blank\" target=\"_blank\" >Supergirl chega aos cinemas em junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-os-casos-de-harry-hole-estreia-na-netflix-nesta-quinta-dia-26\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie &#8216;Os casos de Harry Hole&#8217; estreia na Netflix nesta quinta, dia 26<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/chamas-do-destino-cicek-abre-mao-de-fortuna-para-ficar-com-atlas\/\" class=\"_blank\" target=\"_blank\" >Chamas do Destino:  Cicek abre m\u00e3o de fortuna para ficar com Atlas<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/bridgerton-4at-parte-2-chega-nesta-quinta-26-na-netflix\/\" class=\"_blank\" target=\"_blank\" >Bridgerton (4\u00aaT), parte 2 chega nesta quinta (26), na Netflix<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/programacao-de-filmes-na-tv-para-o-fim-de-semana\/\" class=\"_blank\" target=\"_blank\" >Programa\u00e7\u00e3o de filmes na TV para o fim de semana<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-aniela-chega-na-netflix-dia-11-de-junho\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie Aniela chega na Netflix dia 11 de junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-idade-dourada-t3-estreia-no-max-dia-21-de-junho\/\" class=\"_blank\" target=\"_blank\" >A Idade Dourada (T3) estreia no Max em 21 de junho<\/a><\/h4><\/div><\/div><\/div><\/div><\/div>\n<h2>Filmes e s\u00e9ries<\/h2>\n<p><a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/estreia-na-semana-na-netflix\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias da semana na Netflix<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/o-que-ha-de-novo-no-globoplay\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias e novidades no Globoplay<\/strong><\/a><br \/>\n<a href=\"\/\/tvnovelas.com.br\/filmes\/filmes-em-estreia-nos-cinemas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias e novidades no Cinema<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.tvnovelas.com.br\/novelas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Resumos de novelas<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.tvnovelas.com.br\/tvshow\/filmes-da-globo-na-sessao-da-tarde\/\" rel=\"noopener\" target=\"_blank\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estreia na Netflix nesta segunda, dia 1\/9, a 3\u00aa temporada de Ada Batista, cientista. Esta divertida s\u00e9rie mostra a import\u00e2ncia dos por qu\u00eas. Com produ\u00e7\u00e3o executiva de Chris Nee,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":11689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[92],"tags":[71,70],"class_list":["post-11688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-netflix","tag-estreias-na-netflix","tag-netflix","wpcat-92-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2022\/09\/adabatista.jpg?fit=600%2C360&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-32w","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/11688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=11688"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/11688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/11689"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=11688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=11688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=11688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}