{"id":10912,"date":"2022-07-11T20:20:35","date_gmt":"2022-07-11T23:20:35","guid":{"rendered":"https:\/\/tvnovelas.com.br\/filmes\/?p=10912"},"modified":"2022-07-11T16:28:13","modified_gmt":"2022-07-11T19:28:13","slug":"estreias-na-netflix-nesta-terca-feira-dia-12-de-julho","status":"publish","type":"post","link":"https:\/\/tvnovelas.com.br\/filmes\/estreias-na-netflix-nesta-terca-feira-dia-12-de-julho\/","title":{"rendered":"Estreias na Netflix nesta ter\u00e7a-feira, dia 12 de julho"},"content":{"rendered":"<p><em>Not\u00edcias de estreias na Netflix:<\/em><\/p>\n<h3>Como Mudar sua Mente<\/h3>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2025\/05\/comomudarf.jpg?resize=600%2C360&#038;ssl=1\" alt=\"Foto de Como Mudar sua Mente, em Netflix\" width=\"600\" height=\"360\" class=\"alignnone size-full wp-image-10897\" \/><br \/>\nMiniss\u00e9rie &#8211; Document\u00e1rios<br \/>\n<strong>Estreia em 12 de julho<\/strong><br \/>\nO premiado cineasta Alex Gibney e o escritor best-seller do New York Times Michael Pollan apresentam esta s\u00e9rie documental em quatro partes, cada uma sobre uma subst\u00e2ncia alucin\u00f3gena diferente: LSD, psilocibina, MDMA e mescalina. Com Pollan como guia, exploramos o novo renascimento das drogas psicod\u00e9licas e analisamos contextos hist\u00f3ricos quase esquecidos para explorar o potencial dessas subst\u00e2ncias para curar e alterar mentes e culturas. Como Mudar sua Mente \u00e9 dirigida pela cineasta indicada ao Emmy Alison Ellwood e pela cineasta indicada ao Oscar e vencedora do Emmy Lucy Walker.<\/p>\n<h3>Bill Burr: Ao Vivo no Red Rocks<\/h3>\n<p>Stand-up &#8211; Variedades e divers\u00e3o\/Com\u00e9dia<br \/>\n<strong>Estreia em 12 de julho<\/strong><br \/>\nDireto do deserto montanhoso do Colorado, Bill Burr apresenta seu especial de com\u00e9dia mais recente: Bill Burr: Ao Vivo no Red Rocks. Sempre tentando ser uma pessoa melhor, Bill faz um discurso &#8220;inspirador&#8221; para as mulheres e conta como os cogumelos mudaram a vida dele, como descobriu que tem muitas coisas em comum com as l\u00e9sbicas e como sua filha de 4 anos \u00e9 capaz de ajud\u00e1-lo a controlar a raiva.<br \/>\n<em>Trailer original, em ingl\u00eas<\/em><br \/>\n<iframe width=\"728\" height=\"410\" src=\"https:\/\/www.youtube.com\/embed\/GzFBZY_wEMQ\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3>O Assassino da Minha Filha<\/h3>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2022\/07\/oassassinodeminha.jpg?resize=600%2C360&#038;ssl=1\" alt=\"Foto de O Assassino da Minha Filha\" width=\"600\" height=\"360\" class=\"alignnone size-full wp-image-10913\" \/><br \/>\nFilme &#8211; Document\u00e1rio sobre crimes reais<br \/>\n<strong>Estreia em 12 de julho<\/strong><br \/>\nDepois de lutar durante d\u00e9cadas para levar o assassino da filha \u00e0 justi\u00e7a na Fran\u00e7a e na Alemanha, um pai toma medidas extremas. Document\u00e1rio sobre um crime real.<br \/>\nCom entrevistas e imagens de arquivo, o diretor Antoine Tassin analisa a luta de Andr\u00e9 Bamberski por sua filha Kalinka.<\/p>\n<h3>\u00daltimas not\u00edcias:<\/h3>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-6bd8abdjeq\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/temporada-3-de-euphoria-estreia-domingo-dia-12-4-na-hbo-max\/\" class=\"_blank\" target=\"_blank\" >Temporada 3 de Euphoria estreia domingo, dia 12\/4, na HBO Max<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-netflix-estreia-live-action-de-cavaleiros-do-zodiaco\/\" class=\"_blank\" target=\"_blank\" >A Netflix estreia live-action de Cavaleiros do Zod\u00edaco<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/minha-fera-estreia-no-globoplay-neste-sabado-28-de-marco\/\" class=\"_blank\" target=\"_blank\" >&#8220;Minha Fera&#8221; estreia no Globoplay neste s\u00e1bado, 28 de mar\u00e7o<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/supergirl-chega-aos-cinemas-em-junho\/\" class=\"_blank\" target=\"_blank\" >Supergirl chega aos cinemas em junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-os-casos-de-harry-hole-estreia-na-netflix-nesta-quinta-dia-26\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie &#8216;Os casos de Harry Hole&#8217; estreia na Netflix nesta quinta, dia 26<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/chamas-do-destino-cicek-abre-mao-de-fortuna-para-ficar-com-atlas\/\" class=\"_blank\" target=\"_blank\" >Chamas do Destino:  Cicek abre m\u00e3o de fortuna para ficar com Atlas<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/bridgerton-4at-parte-2-chega-nesta-quinta-26-na-netflix\/\" class=\"_blank\" target=\"_blank\" >Bridgerton (4\u00aaT), parte 2 chega nesta quinta (26), na Netflix<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/programacao-de-filmes-na-tv-para-o-fim-de-semana\/\" class=\"_blank\" target=\"_blank\" >Programa\u00e7\u00e3o de filmes na TV para o fim de semana<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/serie-aniela-chega-na-netflix-dia-11-de-junho\/\" class=\"_blank\" target=\"_blank\" >S\u00e9rie Aniela chega na Netflix dia 11 de junho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/tvnovelas.com.br\/filmes\/a-idade-dourada-t3-estreia-no-max-dia-21-de-junho\/\" class=\"_blank\" target=\"_blank\" >A Idade Dourada (T3) estreia no Max em 21 de junho<\/a><\/h4><\/div><\/div><\/div><\/div><\/div>\n<h3>Filmes e s\u00e9ries<\/h3>\n<p><a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/filmes-e-series-ineditos-em-estreia-na-semana-na-netflix\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias da semana na Netflix<\/strong><\/a><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/filmes\/o-que-ha-de-novo-no-globoplay\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias e novidades no Globoplay<\/strong><\/a><br \/>\n<a href=\"\/\/tvnovelas.com.br\/filmes\/filmes-em-estreia-nos-cinemas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Estreias e novidades no Cinema<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.tvnovelas.com.br\/novelas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Resumos de novelas<\/strong><\/a><br \/>\n<a href=\"https:\/\/caetenews.com.br\/semana\/filmes-da-globo-na-sessao-da-tarde-desta-semana\/\" rel=\"noopener\" target=\"_blank\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Document\u00e1rios &#8216;Como Mudar sua Mente&#8217;,  e &#8216;O Assassino da Minha Filha&#8217;; mais o stand up &#8216;Bill Burr: Ao Vivo&#8217; no Red Rocks&#8217; estreiam na Netflix nesta ter\u00e7a, dia 12<\/p>\n","protected":false},"author":1,"featured_media":10913,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[92],"tags":[71,70],"class_list":["post-10912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-netflix","tag-estreias-na-netflix","tag-netflix","wpcat-92-id"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tvnovelas.com.br\/filmes\/wp-content\/uploads\/2022\/07\/oassassinodeminha.jpg?fit=600%2C360&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcO6EW-2Q0","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/10912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=10912"}],"version-history":[{"count":0,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/posts\/10912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media\/10913"}],"wp:attachment":[{"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=10912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=10912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnovelas.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=10912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}